{"id":65998,"date":"2020-01-08T11:14:55","date_gmt":"2020-01-08T11:14:55","guid":{"rendered":"https:\/\/resources.workable.com\/?p=65998"},"modified":"2020-02-06T13:21:13","modified_gmt":"2020-02-06T13:21:13","slug":"descricao-do-trabalho-community-manager-f-m-d","status":"publish","type":"post","link":"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho","title":{"rendered":"Descri\u00e7\u00e3o do trabalho: Community Manager&nbsp;(f\/m\/d)"},"content":{"rendered":"<p>Este modelo de descri\u00e7\u00e3o do trabalho de um<strong> Community Manager<\/strong> lista as responsabilidades e os requisitos de compet\u00eancia para ajudar voc\u00ea a identificar o candidato ideal para a fun\u00e7\u00e3o, um profissional que possa defender a sua marca. Ele tamb\u00e9m pode ser facilmente personalizado para atender a requisitos de trabalho espec\u00edficos. Cargos similares incluem <a href=\"https:\/\/resources.workable.com\/social-media-coordinator-job-description\">Coordenador de M\u00eddias Sociais<\/a>.<\/p>\n<h2>Responsabilidades do Community Manager incluem:<\/h2>\n<ul>\n<li>Definir e implementar campanhas de m\u00eddia social e de comunica\u00e7\u00e3o para alinhar com estrat\u00e9gias de marketing<\/li>\n<li>Fornecer conte\u00fado atraente de texto, imagem e v\u00eddeo para contas de m\u00eddia social<\/li>\n<li>Responder a coment\u00e1rios e consultas de clientes em tempo h\u00e1bil<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5936\" src=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2016\/07\/community-manager-job-description.jpg\" alt=\"descri\u00e7\u00e3o do trabalho de um community manager\" width=\"640\" height=\"230\" srcset=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2016\/07\/community-manager-job-description.jpg 640w, https:\/\/resources.workable.com\/wp-content\/uploads\/2016\/07\/community-manager-job-description-200x72.jpg 200w, https:\/\/resources.workable.com\/wp-content\/uploads\/2016\/07\/community-manager-job-description-560x201.jpg 560w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este modelo de descri\u00e7\u00e3o do trabalho de um Community Manager lista as responsabilidades e os requisitos de compet\u00eancia para ajudar voc\u00ea a identificar o candidato ideal para a fun\u00e7\u00e3o, um profissional que possa defender a sua marca. Ele tamb\u00e9m pode ser facilmente personalizado para atender a requisitos de trabalho espec\u00edficos. Cargos similares incluem Coordenador de [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"no","_lmt_disable":"","_has_post_settings":[],"footnotes":""},"categories":[1048,1343],"tags":[],"class_list":["post-65998","post","type-post","status-publish","format-standard","hentry","category-descricoes-de-cargo","category-descricoes-do-trabalho-relacionado-com-marketing"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modelo de descri\u00e7\u00e3o de trabalho de um Community Manager | Workable<\/title>\n<meta name=\"description\" content=\"Este modelo de descri\u00e7\u00e3o do trabalho de um Community Manager lista as responsabilidades e os requisitos de compet\u00eancia para ajudar voc\u00ea a identificar o candidato ideal para a fun\u00e7\u00e3o, um profissional que possa defender a sua marca.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modelo de descri\u00e7\u00e3o de trabalho de um Community Manager | Workable\" \/>\n<meta property=\"og:description\" content=\"Este modelo de descri\u00e7\u00e3o do trabalho de um Community Manager lista as responsabilidades e os requisitos de compet\u00eancia para ajudar voc\u00ea a identificar o candidato ideal para a fun\u00e7\u00e3o, um profissional que possa defender a sua marca.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho\" \/>\n<meta property=\"og:site_name\" content=\"Recruiting Resources: How to Recruit and Hire Better\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/workable\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-08T11:14:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-06T13:21:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2016\/07\/community-manager-job-description.jpg\" \/>\n<meta name=\"author\" content=\"Christina Pavlou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@workable\" \/>\n<meta name=\"twitter:site\" content=\"@workable\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina Pavlou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/community-manager-descricao-do-trabalho#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/community-manager-descricao-do-trabalho\"},\"author\":{\"name\":\"Christina Pavlou\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b23289d8d63331621eee9e69103cd603\"},\"headline\":\"Descri\u00e7\u00e3o do trabalho: Community Manager&nbsp;(f\\\/m\\\/d)\",\"datePublished\":\"2020-01-08T11:14:55+00:00\",\"dateModified\":\"2020-02-06T13:21:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/community-manager-descricao-do-trabalho\"},\"wordCount\":124,\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/community-manager-descricao-do-trabalho#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/community-manager-job-description.jpg\",\"articleSection\":[\"Descri\u00e7\u00f5es de cargo\",\"Descri\u00e7\u00f5es do trabalho relacionado com marketing\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/community-manager-descricao-do-trabalho\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/community-manager-descricao-do-trabalho\",\"name\":\"Modelo de descri\u00e7\u00e3o de trabalho de um Community Manager | Workable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/community-manager-descricao-do-trabalho#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/community-manager-descricao-do-trabalho#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/community-manager-job-description.jpg\",\"datePublished\":\"2020-01-08T11:14:55+00:00\",\"dateModified\":\"2020-02-06T13:21:13+00:00\",\"description\":\"Este modelo de descri\u00e7\u00e3o do trabalho de um Community Manager lista as responsabilidades e os requisitos de compet\u00eancia para ajudar voc\u00ea a identificar o candidato ideal para a fun\u00e7\u00e3o, um profissional que possa defender a sua marca.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/community-manager-descricao-do-trabalho#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/community-manager-descricao-do-trabalho\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/community-manager-descricao-do-trabalho#primaryimage\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/community-manager-job-description.jpg\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/community-manager-job-description.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/community-manager-descricao-do-trabalho#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descri\u00e7\u00e3o do trabalho: Community Manager&nbsp;(f\\\/m\\\/d)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/\",\"name\":\"Recruiting Resources: How to Recruit and Hire Better\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/#organization\",\"name\":\"Workable\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"width\":150,\"height\":25,\"caption\":\"Workable\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/business.facebook.com\\\/workable\\\/\",\"https:\\\/\\\/x.com\\\/workable\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/workable-hr\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/b23289d8d63331621eee9e69103cd603\",\"name\":\"Christina Pavlou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg\",\"caption\":\"Christina Pavlou\"},\"description\":\"Christina Pavlou was a writer at Workable for nearly four years, and previously a recruiter. She writes about diversity in the workplace and reports on the shape of things to come. You can find her on LinkedIn and Twitter.\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/pt-br\\\/author\\\/christina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modelo de descri\u00e7\u00e3o de trabalho de um Community Manager | Workable","description":"Este modelo de descri\u00e7\u00e3o do trabalho de um Community Manager lista as responsabilidades e os requisitos de compet\u00eancia para ajudar voc\u00ea a identificar o candidato ideal para a fun\u00e7\u00e3o, um profissional que possa defender a sua marca.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho\/","og_locale":"pt_BR","og_type":"article","og_title":"Modelo de descri\u00e7\u00e3o de trabalho de um Community Manager | Workable","og_description":"Este modelo de descri\u00e7\u00e3o do trabalho de um Community Manager lista as responsabilidades e os requisitos de compet\u00eancia para ajudar voc\u00ea a identificar o candidato ideal para a fun\u00e7\u00e3o, um profissional que possa defender a sua marca.","og_url":"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho","og_site_name":"Recruiting Resources: How to Recruit and Hire Better","article_publisher":"https:\/\/business.facebook.com\/workable\/","article_published_time":"2020-01-08T11:14:55+00:00","article_modified_time":"2020-02-06T13:21:13+00:00","og_image":[{"url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2016\/07\/community-manager-job-description.jpg","type":"","width":"","height":""}],"author":"Christina Pavlou","twitter_card":"summary_large_image","twitter_creator":"@workable","twitter_site":"@workable","twitter_misc":{"Escrito por":"Christina Pavlou","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho#article","isPartOf":{"@id":"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho"},"author":{"name":"Christina Pavlou","@id":"https:\/\/resources.workable.com\/pt-br\/#\/schema\/person\/b23289d8d63331621eee9e69103cd603"},"headline":"Descri\u00e7\u00e3o do trabalho: Community Manager&nbsp;(f\/m\/d)","datePublished":"2020-01-08T11:14:55+00:00","dateModified":"2020-02-06T13:21:13+00:00","mainEntityOfPage":{"@id":"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho"},"wordCount":124,"publisher":{"@id":"https:\/\/resources.workable.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2016\/07\/community-manager-job-description.jpg","articleSection":["Descri\u00e7\u00f5es de cargo","Descri\u00e7\u00f5es do trabalho relacionado com marketing"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho","url":"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho","name":"Modelo de descri\u00e7\u00e3o de trabalho de um Community Manager | Workable","isPartOf":{"@id":"https:\/\/resources.workable.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho#primaryimage"},"image":{"@id":"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2016\/07\/community-manager-job-description.jpg","datePublished":"2020-01-08T11:14:55+00:00","dateModified":"2020-02-06T13:21:13+00:00","description":"Este modelo de descri\u00e7\u00e3o do trabalho de um Community Manager lista as responsabilidades e os requisitos de compet\u00eancia para ajudar voc\u00ea a identificar o candidato ideal para a fun\u00e7\u00e3o, um profissional que possa defender a sua marca.","breadcrumb":{"@id":"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho#primaryimage","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2016\/07\/community-manager-job-description.jpg","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2016\/07\/community-manager-job-description.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/resources.workable.com\/pt-br\/community-manager-descricao-do-trabalho#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/resources.workable.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Descri\u00e7\u00e3o do trabalho: Community Manager&nbsp;(f\/m\/d)"}]},{"@type":"WebSite","@id":"https:\/\/resources.workable.com\/pt-br\/#website","url":"https:\/\/resources.workable.com\/pt-br\/","name":"Recruiting Resources: How to Recruit and Hire Better","description":"","publisher":{"@id":"https:\/\/resources.workable.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/resources.workable.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/resources.workable.com\/pt-br\/#organization","name":"Workable","url":"https:\/\/resources.workable.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/resources.workable.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","width":150,"height":25,"caption":"Workable"},"image":{"@id":"https:\/\/resources.workable.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/workable\/","https:\/\/x.com\/workable","https:\/\/www.linkedin.com\/company\/workable-hr\/"]},{"@type":"Person","@id":"https:\/\/resources.workable.com\/pt-br\/#\/schema\/person\/b23289d8d63331621eee9e69103cd603","name":"Christina Pavlou","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg","caption":"Christina Pavlou"},"description":"Christina Pavlou was a writer at Workable for nearly four years, and previously a recruiter. She writes about diversity in the workplace and reports on the shape of things to come. You can find her on LinkedIn and Twitter.","url":"https:\/\/resources.workable.com\/pt-br\/author\/christina\/"}]}},"modified_by":"Zina Panagopoulou","custom_fields":{"brief":"Estamos procurando um Community Manager qualificado para fazer parte de nossa equipe. Se voc\u00ea for um profissional experiente em tecnologia, m\u00eddia social, rela\u00e7\u00f5es p\u00fablicas e eventos promocionais, gostar\u00edamos de conhec\u00ea-lo.\r\n\r\nNosso candidato ideal possui habilidades excepcionais de comunica\u00e7\u00e3o oral e escrita e \u00e9 capaz de desenvolver um conte\u00fado envolvente. Ele deve ser \"soci\u00e1vel\", al\u00e9m de ter \u00f3timas habilidades de atendimento ao cliente e capacidade de moderar conversas on-line e off-line com nossa comunidade.\r\n\r\nBasicamente, o candidato selecionado dever\u00e1 ser capaz de atuar como a imagem e a voz da nossa marca e gerenciar todas as comunica\u00e7\u00f5es da comunidade.","requirements":"<ul>\r\n \t<li>Experi\u00eancia profissional comprovada como community manager<\/li>\r\n \t<li>Experi\u00eancia em lan\u00e7ar iniciativas comunit\u00e1rias (por exemplo, criar um f\u00f3rum on-line, iniciar um programa de embaixador, criar uma s\u00e9rie de eventos e escrever um boletim informativo por e-mail)<\/li>\r\n \t<li>Capacidade de identificar e acompanhar as m\u00e9tricas relevantes da comunidade (por exemplo, presen\u00e7a repetida em eventos)<\/li>\r\n \t<li>Excelentes habilidades de comunica\u00e7\u00e3o verbal<\/li>\r\n \t<li>Excelentes habilidades de reda\u00e7\u00e3o<\/li>\r\n \t<li>Experi\u00eancia pr\u00e1tica com gerenciamento de m\u00eddia social para marcas<\/li>\r\n \t<li>Capacidade de interpretar o tr\u00e1fego do site e as m\u00e9tricas de envolvimento do cliente on-line<\/li>\r\n \t<li>Conhecimento de marketing on-line e canais de marketing<\/li>\r\n \t<li>Aten\u00e7\u00e3o aos detalhes e habilidade para realizar v\u00e1rias tarefas<\/li>\r\n \t<li>Bacharelado em Marketing ou \u00e1rea relacionada<\/li>\r\n<\/ul>","responsibilities":"<ul>\r\n \t<li>Definir e implementar campanhas de m\u00eddia social e de comunica\u00e7\u00e3o para alinhar com estrat\u00e9gias de marketing<\/li>\r\n \t<li>Fornecer conte\u00fado atraente de texto, imagem e v\u00eddeo para contas de m\u00eddia social<\/li>\r\n \t<li>Responder a coment\u00e1rios e consultas de clientes em tempo h\u00e1bil<\/li>\r\n \t<li>Monitorar e relatar coment\u00e1rios e an\u00e1lises on-line<\/li>\r\n \t<li>Organizar e participar de eventos para desenvolver a comunidade e aumentar o reconhecimento da marca<\/li>\r\n \t<li>Coordenar com as equipes de Marketing, Rela\u00e7\u00f5es P\u00fablicas e Comunica\u00e7\u00e3o para garantir a uniformidade da marca<\/li>\r\n \t<li>Interagir com os departamentos de Desenvolvimento e Vendas para se manter atualizado sobre novos produtos e recursos<\/li>\r\n \t<li>Construir relacionamento com clientes, clientes em potencial, profissionais do setor e jornalistas<\/li>\r\n \t<li>Manter-se atualizado com novas tend\u00eancias em tecnologia digital<\/li>\r\n<\/ul>","see_more":""},"_links":{"self":[{"href":"https:\/\/resources.workable.com\/pt-br\/wp-json\/wp\/v2\/posts\/65998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resources.workable.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resources.workable.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/pt-br\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/pt-br\/wp-json\/wp\/v2\/comments?post=65998"}],"version-history":[{"count":0,"href":"https:\/\/resources.workable.com\/pt-br\/wp-json\/wp\/v2\/posts\/65998\/revisions"}],"wp:attachment":[{"href":"https:\/\/resources.workable.com\/pt-br\/wp-json\/wp\/v2\/media?parent=65998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resources.workable.com\/pt-br\/wp-json\/wp\/v2\/categories?post=65998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resources.workable.com\/pt-br\/wp-json\/wp\/v2\/tags?post=65998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}