{"id":51289,"date":"2020-01-08T11:08:27","date_gmt":"2020-01-08T11:08:27","guid":{"rendered":"https:\/\/resources.workable.com\/?p=51289"},"modified":"2020-02-06T13:15:46","modified_gmt":"2020-02-06T13:15:46","slug":"descriptif-de-poste-assistant-achats-f-h-autre","status":"publish","type":"post","link":"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste","title":{"rendered":"Descriptif de poste: Assistant achats&nbsp;(f\/h\/autre)"},"content":{"rendered":"<p>Il s&rsquo;agit d&rsquo;un mod\u00e8le de fiche de poste d&rsquo;assistant(e) achats destin\u00e9 \u00e0 vous aider \u00e0 attirer les candidats les plus qualifi\u00e9s. Pour plus de postes de niveau sup\u00e9rieur, consultez notre <a href=\"https:\/\/resources.workable.com\/purchasing-manager-job-description\" target=\"_blank\" rel=\"noopener noreferrer\">fiche de poste de responsable achats<\/a>.<\/p>\n<h2>Responsabilit\u00e9s de l&rsquo;assistant(e) achats:<\/h2>\n<ul>\n<li>Surveiller les niveaux de stock et identifier les besoins d&rsquo;achat<\/li>\n<li>Rechercher les vendeurs potentiels<\/li>\n<li>Suivre les commandes et assurer une livraison rapide<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-24211 alignnone\" src=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/09\/shutterstock_709417909.jpg\" alt=\"fiche de poste d'assistant(e) achats \" width=\"640\" height=\"230\" srcset=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/09\/shutterstock_709417909.jpg 640w, https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/09\/shutterstock_709417909-200x72.jpg 200w, https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/09\/shutterstock_709417909-560x201.jpg 560w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il s&rsquo;agit d&rsquo;un mod\u00e8le de fiche de poste d&rsquo;assistant(e) achats destin\u00e9 \u00e0 vous aider \u00e0 attirer les candidats les plus qualifi\u00e9s. Pour plus de postes de niveau sup\u00e9rieur, consultez notre fiche de poste de responsable achats. Responsabilit\u00e9s de l&rsquo;assistant(e) achats: Surveiller les niveaux de stock et identifier les besoins d&rsquo;achat Rechercher les vendeurs potentiels Suivre [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"no","_lmt_disable":"","_has_post_settings":[],"footnotes":""},"categories":[1041,1292],"tags":[],"class_list":["post-51289","post","type-post","status-publish","format-standard","hentry","category-descriptifs-de-postes","category-descriptifs-de-postes-logistique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mod\u00e8le de fiche de poste d&#039;assistant(e) achats | Workable<\/title>\n<meta name=\"description\" content=\"Il s&#039;agit d&#039;un mod\u00e8le de fiche de poste d&#039;assistant(e) achats destin\u00e9 \u00e0 vous aider \u00e0 attirer les candidats les plus qualifi\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mod\u00e8le de fiche de poste d&#039;assistant(e) achats | Workable\" \/>\n<meta property=\"og:description\" content=\"Il s&#039;agit d&#039;un mod\u00e8le de fiche de poste d&#039;assistant(e) achats destin\u00e9 \u00e0 vous aider \u00e0 attirer les candidats les plus qualifi\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste\" \/>\n<meta property=\"og:site_name\" content=\"Recruiting Resources: How to Recruit and Hire Better\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/workable\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-08T11:08:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-06T13:15:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/09\/shutterstock_709417909.jpg\" \/>\n<meta name=\"author\" content=\"Christina Pavlou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@workable\" \/>\n<meta name=\"twitter:site\" content=\"@workable\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina Pavlou\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/assistant-achats-descriptif-de-poste#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/assistant-achats-descriptif-de-poste\"},\"author\":{\"name\":\"Christina Pavlou\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#\\\/schema\\\/person\\\/b23289d8d63331621eee9e69103cd603\"},\"headline\":\"Descriptif de poste: Assistant achats&nbsp;(f\\\/h\\\/autre)\",\"datePublished\":\"2020-01-08T11:08:27+00:00\",\"dateModified\":\"2020-02-06T13:15:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/assistant-achats-descriptif-de-poste\"},\"wordCount\":79,\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/assistant-achats-descriptif-de-poste#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/shutterstock_709417909.jpg\",\"articleSection\":[\"Descriptifs de postes\",\"Descriptifs de postes Logistique\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/assistant-achats-descriptif-de-poste\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/assistant-achats-descriptif-de-poste\",\"name\":\"Mod\u00e8le de fiche de poste d'assistant(e) achats | Workable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/assistant-achats-descriptif-de-poste#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/assistant-achats-descriptif-de-poste#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/shutterstock_709417909.jpg\",\"datePublished\":\"2020-01-08T11:08:27+00:00\",\"dateModified\":\"2020-02-06T13:15:46+00:00\",\"description\":\"Il s'agit d'un mod\u00e8le de fiche de poste d'assistant(e) achats destin\u00e9 \u00e0 vous aider \u00e0 attirer les candidats les plus qualifi\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/assistant-achats-descriptif-de-poste#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/resources.workable.com\\\/fr\\\/assistant-achats-descriptif-de-poste\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/assistant-achats-descriptif-de-poste#primaryimage\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/shutterstock_709417909.jpg\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/shutterstock_709417909.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/assistant-achats-descriptif-de-poste#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descriptif de poste: Assistant achats&nbsp;(f\\\/h\\\/autre)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/\",\"name\":\"Recruiting Resources: How to Recruit and Hire Better\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#organization\",\"name\":\"Workable\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"width\":150,\"height\":25,\"caption\":\"Workable\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/business.facebook.com\\\/workable\\\/\",\"https:\\\/\\\/x.com\\\/workable\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/workable-hr\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#\\\/schema\\\/person\\\/b23289d8d63331621eee9e69103cd603\",\"name\":\"Christina Pavlou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg\",\"caption\":\"Christina Pavlou\"},\"description\":\"Christina Pavlou was a writer at Workable for nearly four years, and previously a recruiter. She writes about diversity in the workplace and reports on the shape of things to come. You can find her on LinkedIn and Twitter.\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/author\\\/christina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mod\u00e8le de fiche de poste d'assistant(e) achats | Workable","description":"Il s'agit d'un mod\u00e8le de fiche de poste d'assistant(e) achats destin\u00e9 \u00e0 vous aider \u00e0 attirer les candidats les plus qualifi\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste\/","og_locale":"fr_FR","og_type":"article","og_title":"Mod\u00e8le de fiche de poste d'assistant(e) achats | Workable","og_description":"Il s'agit d'un mod\u00e8le de fiche de poste d'assistant(e) achats destin\u00e9 \u00e0 vous aider \u00e0 attirer les candidats les plus qualifi\u00e9s.","og_url":"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste","og_site_name":"Recruiting Resources: How to Recruit and Hire Better","article_publisher":"https:\/\/business.facebook.com\/workable\/","article_published_time":"2020-01-08T11:08:27+00:00","article_modified_time":"2020-02-06T13:15:46+00:00","og_image":[{"url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/09\/shutterstock_709417909.jpg","type":"","width":"","height":""}],"author":"Christina Pavlou","twitter_card":"summary_large_image","twitter_creator":"@workable","twitter_site":"@workable","twitter_misc":{"\u00c9crit par":"Christina Pavlou"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste#article","isPartOf":{"@id":"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste"},"author":{"name":"Christina Pavlou","@id":"https:\/\/resources.workable.com\/fr\/#\/schema\/person\/b23289d8d63331621eee9e69103cd603"},"headline":"Descriptif de poste: Assistant achats&nbsp;(f\/h\/autre)","datePublished":"2020-01-08T11:08:27+00:00","dateModified":"2020-02-06T13:15:46+00:00","mainEntityOfPage":{"@id":"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste"},"wordCount":79,"publisher":{"@id":"https:\/\/resources.workable.com\/fr\/#organization"},"image":{"@id":"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/09\/shutterstock_709417909.jpg","articleSection":["Descriptifs de postes","Descriptifs de postes Logistique"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste","url":"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste","name":"Mod\u00e8le de fiche de poste d'assistant(e) achats | Workable","isPartOf":{"@id":"https:\/\/resources.workable.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste#primaryimage"},"image":{"@id":"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/09\/shutterstock_709417909.jpg","datePublished":"2020-01-08T11:08:27+00:00","dateModified":"2020-02-06T13:15:46+00:00","description":"Il s'agit d'un mod\u00e8le de fiche de poste d'assistant(e) achats destin\u00e9 \u00e0 vous aider \u00e0 attirer les candidats les plus qualifi\u00e9s.","breadcrumb":{"@id":"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste#primaryimage","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/09\/shutterstock_709417909.jpg","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/09\/shutterstock_709417909.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/resources.workable.com\/fr\/assistant-achats-descriptif-de-poste#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/resources.workable.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Descriptif de poste: Assistant achats&nbsp;(f\/h\/autre)"}]},{"@type":"WebSite","@id":"https:\/\/resources.workable.com\/fr\/#website","url":"https:\/\/resources.workable.com\/fr\/","name":"Recruiting Resources: How to Recruit and Hire Better","description":"","publisher":{"@id":"https:\/\/resources.workable.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/resources.workable.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/resources.workable.com\/fr\/#organization","name":"Workable","url":"https:\/\/resources.workable.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/resources.workable.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","width":150,"height":25,"caption":"Workable"},"image":{"@id":"https:\/\/resources.workable.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/workable\/","https:\/\/x.com\/workable","https:\/\/www.linkedin.com\/company\/workable-hr\/"]},{"@type":"Person","@id":"https:\/\/resources.workable.com\/fr\/#\/schema\/person\/b23289d8d63331621eee9e69103cd603","name":"Christina Pavlou","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg","caption":"Christina Pavlou"},"description":"Christina Pavlou was a writer at Workable for nearly four years, and previously a recruiter. She writes about diversity in the workplace and reports on the shape of things to come. You can find her on LinkedIn and Twitter.","url":"https:\/\/resources.workable.com\/fr\/author\/christina\/"}]}},"modified_by":null,"custom_fields":{"brief":"Nous recherchons un(e) assistant(e) achats pour commander des fournitures et du mat\u00e9riel en fonction des besoins de notre soci\u00e9t\u00e9.\r\n\r\nLes responsabilit\u00e9s de l'assistant(e) achats incluent la recherche de nouveaux fournisseurs, le suivi des livraisons et la mise \u00e0 jour des enregistrements des commandes (par exemple, les dates, les factures et les remises). Si vous connaissez les proc\u00e9dures de la cha\u00eene d'approvisionnement et savez comment cr\u00e9er et traduire des analyses de co\u00fbts, nous aimerions vous rencontrer.\r\n\r\nEn fin de compte, vous effectuerez des achats rentables et veillerez \u00e0 ce que nous conservions un stock enti\u00e8rement approvisionn\u00e9.","requirements":"<ul>\r\n \t<li>Exp\u00e9rience professionnelle en tant qu'assistant financier, <a href=\"https:\/\/resources.workable.com\/purchasing-officer-job-description\" target=\"_blank\" rel=\"noopener\">responsable financier<\/a> ou \u00e0 un poste similaire<\/li>\r\n \t<li>Bonne compr\u00e9hension des proc\u00e9dures de la cha\u00eene d'approvisionnement<\/li>\r\n \t<li>Exp\u00e9rience pratique de l'achat de logiciels (par ex. Procurify ou SpendMap)<\/li>\r\n \t<li>Bonnes connaissances de MS Excel<\/li>\r\n \t<li>Connaissance des m\u00e9thodes de recherche<\/li>\r\n \t<li>Fortes comp\u00e9tences organisationnelles<\/li>\r\n \t<li>Licence en logistique, administration d'entreprises ou dans un domaine pertinent<\/li>\r\n<\/ul>","responsibilities":"<ul>\r\n \t<li>Surveiller les niveaux de stock et identifier les besoins d'achat<\/li>\r\n \t<li>Rechercher les vendeurs potentiels<\/li>\r\n \t<li>Suivre les commandes et assurer une livraison rapide<\/li>\r\n \t<li>Mettre \u00e0 jour les bases de donn\u00e9es internes avec les d\u00e9tails de la commande (dates, fournisseurs, quantit\u00e9s, remises)<\/li>\r\n \t<li>Effectuer une \u00e9tude de march\u00e9 pour identifier les tendances en mati\u00e8re de prix<\/li>\r\n \t<li>\u00c9valuer les offres des vendeurs et n\u00e9gocier de meilleurs prix<\/li>\r\n \t<li>Pr\u00e9parer les analyses de co\u00fbts<\/li>\r\n \t<li>Conserver les fichiers num\u00e9riques et physiques des factures et des contrats<\/li>\r\n \t<li>Faire un suivi avec les fournisseurs, au besoin, pour confirmer ou modifier les commandes<\/li>\r\n \t<li>Assurer la liaison avec le personnel de l'entrep\u00f4t pour s'assurer que tous les produits arrivent en bon \u00e9tat<\/li>\r\n<\/ul>","see_more":""},"_links":{"self":[{"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/posts\/51289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/comments?post=51289"}],"version-history":[{"count":0,"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/posts\/51289\/revisions"}],"wp:attachment":[{"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/media?parent=51289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/categories?post=51289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/tags?post=51289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}