{"id":49382,"date":"2020-01-08T11:07:39","date_gmt":"2020-01-08T11:07:39","guid":{"rendered":"https:\/\/resources.workable.com\/?p=49382"},"modified":"2020-02-06T13:20:44","modified_gmt":"2020-02-06T13:20:44","slug":"descriptif-de-poste-recruteur-f-h-autre","status":"publish","type":"post","link":"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste","title":{"rendered":"Descriptif de poste: Recruteur&nbsp;(f\/h\/autre)"},"content":{"rendered":"<p>Ce mod\u00e8le de descriptif de poste de Recruteur(se) est optimis\u00e9 pour \u00eatre publi\u00e9 sur les sites d&rsquo;annonces en ligne afin d&rsquo;attirer des candidats qualifi\u00e9s qui pourront g\u00e9rer tout le cycle de recrutement de la soci\u00e9t\u00e9. Vous pouvez facilement le personnaliser selon les crit\u00e8res sp\u00e9cifiques que vous recherchez chez un(e) recruteur(se): recrutement interne, dotation en personnel, technique, etc. Intitul\u00e9s de poste similaires: <a href=\"https:\/\/resources.workable.com\/hr-recruiter-job-description\">Recruteur(se) RH<\/a>,\u00a0<a href=\"https:\/\/resources.workable.com\/internal-recruiter-job-description\">Recruteur(se) interne<\/a>, <a href=\"https:\/\/resources.workable.com\/campus-recruiter-job-description\">Recruteur(se) campus<\/a>, <a href=\"https:\/\/resources.workable.com\/technical-recruiter-job-description\">Recruteur(se) technique<\/a>, <a href=\"https:\/\/resources.workable.com\/executive-recruiter-job-description\">Recruteur de cadres sup\u00e9rieurs<\/a> et\u00a0<a href=\"https:\/\/resources.workable.com\/recruitment-manager-job-description\">Responsable recrutement.<\/a><\/p>\n<h2>Les responsabilit\u00e9s du\/de la recruteur(se) incluent:<\/h2>\n<ul>\n<li>\u00c9laborer et mettre en place la strat\u00e9gie globale de recrutement<\/li>\n<li>Trouver et recruter des candidats en utilisant les bases de donn\u00e9es, les r\u00e9seaux sociaux, etc.<\/li>\n<li>R\u00e9aliser les entretiens et filtrer les candidats pour les postes \u00e0 pourvoir<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-49385 alignnone\" src=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/recruiter-640x230.jpg\" alt=\"Descriptif de poste de recruteur(se)\" width=\"640\" height=\"230\" srcset=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/recruiter.jpg 640w, https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/recruiter-200x72.jpg 200w, https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/recruiter-560x201.jpg 560w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><em><strong>Vous souhaitez embaucher un(e) recruteur(se)\u00a0? Inscrivez-vous <a href=\"https:\/\/www.workable.com\/post-jobs-for-free\/customize?wid=542&amp;utm_page=recruiter-job-description&amp;utm_program=ad-unit-right&amp;utm_tracking=job-descriptions-human-resources-job-descriptions\">pour un essai gratuit d&rsquo;une dur\u00e9e de 15 jours avec Workable<\/a> pour publier une annonce pour ce poste et embaucher mieux et plus rapidement.<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce mod\u00e8le de descriptif de poste de Recruteur(se) est optimis\u00e9 pour \u00eatre publi\u00e9 sur les sites d&rsquo;annonces en ligne afin d&rsquo;attirer des candidats qualifi\u00e9s qui pourront g\u00e9rer tout le cycle de recrutement de la soci\u00e9t\u00e9. Vous pouvez facilement le personnaliser selon les crit\u00e8res sp\u00e9cifiques que vous recherchez chez un(e) recruteur(se): recrutement interne, dotation en personnel, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"no","_lmt_disable":"","_has_post_settings":[],"footnotes":""},"categories":[1041,1283],"tags":[1282],"class_list":["post-49382","post","type-post","status-publish","format-standard","hentry","category-descriptifs-de-postes","category-descriptifs-de-postes-dans-les-ressources-humaines-rh","tag-sample-hr-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mod\u00e8le de descriptif de poste de recruteur(se) | Workable<\/title>\n<meta name=\"description\" content=\"Vous souhaitez embaucher un(e) recruteur(se)\u00a0? Utilisez ce descriptif de poste pour trouver des candidats \u00e0 votre poste de recruteur(se) interne, d&#039;agence ou technique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mod\u00e8le de descriptif de poste de recruteur(se) | Workable\" \/>\n<meta property=\"og:description\" content=\"Vous souhaitez embaucher un(e) recruteur(se)\u00a0? Utilisez ce descriptif de poste pour trouver des candidats \u00e0 votre poste de recruteur(se) interne, d&#039;agence ou technique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste\" \/>\n<meta property=\"og:site_name\" content=\"Recruiting Resources: How to Recruit and Hire Better\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/workable\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-08T11:07:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-06T13:20:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/recruiter-640x230.jpg\" \/>\n<meta name=\"author\" content=\"Eleni Kourmentza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@workable\" \/>\n<meta name=\"twitter:site\" content=\"@workable\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eleni Kourmentza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/recruteur-descriptif-de-poste#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/recruteur-descriptif-de-poste\"},\"author\":{\"name\":\"Eleni Kourmentza\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#\\\/schema\\\/person\\\/246aec99718ddcb172f71f699e088a88\"},\"headline\":\"Descriptif de poste: Recruteur&nbsp;(f\\\/h\\\/autre)\",\"datePublished\":\"2020-01-08T11:07:39+00:00\",\"dateModified\":\"2020-02-06T13:20:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/recruteur-descriptif-de-poste\"},\"wordCount\":182,\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/recruteur-descriptif-de-poste#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/recruiter-640x230.jpg\",\"keywords\":[\"sample-hr\"],\"articleSection\":[\"Descriptifs de postes\",\"Descriptifs de postes dans les Ressources humaines (RH)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/recruteur-descriptif-de-poste\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/recruteur-descriptif-de-poste\",\"name\":\"Mod\u00e8le de descriptif de poste de recruteur(se) | Workable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/recruteur-descriptif-de-poste#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/recruteur-descriptif-de-poste#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/recruiter-640x230.jpg\",\"datePublished\":\"2020-01-08T11:07:39+00:00\",\"dateModified\":\"2020-02-06T13:20:44+00:00\",\"description\":\"Vous souhaitez embaucher un(e) recruteur(se)\u00a0? Utilisez ce descriptif de poste pour trouver des candidats \u00e0 votre poste de recruteur(se) interne, d'agence ou technique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/recruteur-descriptif-de-poste#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/resources.workable.com\\\/fr\\\/recruteur-descriptif-de-poste\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/recruteur-descriptif-de-poste#primaryimage\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/recruiter-640x230.jpg\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/recruiter-640x230.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/recruteur-descriptif-de-poste#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descriptif de poste: Recruteur&nbsp;(f\\\/h\\\/autre)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/\",\"name\":\"Recruiting Resources: How to Recruit and Hire Better\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#organization\",\"name\":\"Workable\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"width\":150,\"height\":25,\"caption\":\"Workable\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/business.facebook.com\\\/workable\\\/\",\"https:\\\/\\\/x.com\\\/workable\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/workable-hr\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/#\\\/schema\\\/person\\\/246aec99718ddcb172f71f699e088a88\",\"name\":\"Eleni Kourmentza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg\",\"caption\":\"Eleni Kourmentza\"},\"description\":\"Eleni Kourmentza, ex-People Ops Manager at Workable, excelled in recruitment, lifecycle management, HR admin, culture nurturing, and employer branding.\",\"sameAs\":[\"http:\\\/\\\/workable.com\"],\"url\":\"https:\\\/\\\/resources.workable.com\\\/fr\\\/author\\\/eleni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mod\u00e8le de descriptif de poste de recruteur(se) | Workable","description":"Vous souhaitez embaucher un(e) recruteur(se)\u00a0? Utilisez ce descriptif de poste pour trouver des candidats \u00e0 votre poste de recruteur(se) interne, d'agence ou technique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste\/","og_locale":"fr_FR","og_type":"article","og_title":"Mod\u00e8le de descriptif de poste de recruteur(se) | Workable","og_description":"Vous souhaitez embaucher un(e) recruteur(se)\u00a0? Utilisez ce descriptif de poste pour trouver des candidats \u00e0 votre poste de recruteur(se) interne, d'agence ou technique.","og_url":"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste","og_site_name":"Recruiting Resources: How to Recruit and Hire Better","article_publisher":"https:\/\/business.facebook.com\/workable\/","article_published_time":"2020-01-08T11:07:39+00:00","article_modified_time":"2020-02-06T13:20:44+00:00","og_image":[{"url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/recruiter-640x230.jpg","type":"","width":"","height":""}],"author":"Eleni Kourmentza","twitter_card":"summary_large_image","twitter_creator":"@workable","twitter_site":"@workable","twitter_misc":{"\u00c9crit par":"Eleni Kourmentza","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste#article","isPartOf":{"@id":"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste"},"author":{"name":"Eleni Kourmentza","@id":"https:\/\/resources.workable.com\/fr\/#\/schema\/person\/246aec99718ddcb172f71f699e088a88"},"headline":"Descriptif de poste: Recruteur&nbsp;(f\/h\/autre)","datePublished":"2020-01-08T11:07:39+00:00","dateModified":"2020-02-06T13:20:44+00:00","mainEntityOfPage":{"@id":"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste"},"wordCount":182,"publisher":{"@id":"https:\/\/resources.workable.com\/fr\/#organization"},"image":{"@id":"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/recruiter-640x230.jpg","keywords":["sample-hr"],"articleSection":["Descriptifs de postes","Descriptifs de postes dans les Ressources humaines (RH)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste","url":"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste","name":"Mod\u00e8le de descriptif de poste de recruteur(se) | Workable","isPartOf":{"@id":"https:\/\/resources.workable.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste#primaryimage"},"image":{"@id":"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/recruiter-640x230.jpg","datePublished":"2020-01-08T11:07:39+00:00","dateModified":"2020-02-06T13:20:44+00:00","description":"Vous souhaitez embaucher un(e) recruteur(se)\u00a0? Utilisez ce descriptif de poste pour trouver des candidats \u00e0 votre poste de recruteur(se) interne, d'agence ou technique.","breadcrumb":{"@id":"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste#primaryimage","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/recruiter-640x230.jpg","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/recruiter-640x230.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/resources.workable.com\/fr\/recruteur-descriptif-de-poste#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/resources.workable.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Descriptif de poste: Recruteur&nbsp;(f\/h\/autre)"}]},{"@type":"WebSite","@id":"https:\/\/resources.workable.com\/fr\/#website","url":"https:\/\/resources.workable.com\/fr\/","name":"Recruiting Resources: How to Recruit and Hire Better","description":"","publisher":{"@id":"https:\/\/resources.workable.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/resources.workable.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/resources.workable.com\/fr\/#organization","name":"Workable","url":"https:\/\/resources.workable.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/resources.workable.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","width":150,"height":25,"caption":"Workable"},"image":{"@id":"https:\/\/resources.workable.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/workable\/","https:\/\/x.com\/workable","https:\/\/www.linkedin.com\/company\/workable-hr\/"]},{"@type":"Person","@id":"https:\/\/resources.workable.com\/fr\/#\/schema\/person\/246aec99718ddcb172f71f699e088a88","name":"Eleni Kourmentza","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg","caption":"Eleni Kourmentza"},"description":"Eleni Kourmentza, ex-People Ops Manager at Workable, excelled in recruitment, lifecycle management, HR admin, culture nurturing, and employer branding.","sameAs":["http:\/\/workable.com"],"url":"https:\/\/resources.workable.com\/fr\/author\/eleni\/"}]}},"modified_by":"Zina Panagopoulou","custom_fields":{"brief":"Nous recherchons un(e) recruteur(se) ayant l'exp\u00e9rience de tout le cycle de recrutement, de la <a href=\"https:\/\/resources.workable.com\/blog\/filling-your-talent-pool\" target=\"_blank\" rel=\"noopener noreferrer\">recherche de candidats<\/a> \u00e0 l'embauche d'excellents employ\u00e9s, en passant par la phase d'entretiens.\r\n<h3>En quoi consiste le travail d'un(e) recruteur(se)\u00a0?<\/h3>\r\n<a href=\"https:\/\/resources.workable.com\/tutorial\/good-recruiter\">Un(e) bon(ne) recruteur(se)<\/a> coop\u00e9rera r\u00e9guli\u00e8rement avec les chefs de service pour identifier les futurs besoins de recrutement. Vous devrez \u00e9galement pouvoir attirer des candidats \u00e0 l'aide de diff\u00e9rentes sources, comme les r\u00e9seaux sociaux et les <a href=\"https:\/\/resources.workable.com\/tutorial\/how-to-build-employee-referral-program\/\" target=\"_blank\" rel=\"noopener noreferrer\">recommandations des employ\u00e9s<\/a>. Notre recruteur(se) id\u00e9al(e) poss\u00e8de un bagage universitaire dans les RH, associ\u00e9 \u00e0 une exp\u00e9rience professionnelle des phases de pr\u00e9-s\u00e9lection, entretien et \u00e9valuation des candidats.\r\n\r\nPour r\u00e9sumer, le\/la recruteur(se) sera en charge de s'assurer que notre soci\u00e9t\u00e9 attire, embauche et <a href=\"https:\/\/resources.workable.com\/tutorial\/employee-retention-program\" target=\"_blank\" rel=\"noopener noreferrer\">retienne<\/a> les meilleurs employ\u00e9s, tout en cr\u00e9ant une <a href=\"https:\/\/resources.workable.com\/blog\/talent-pipeline\" target=\"_blank\" rel=\"noopener noreferrer\">forte r\u00e9serve de talents<\/a>.","requirements":"<ul>\r\n \t<li>Exp\u00e9rience professionnelle av\u00e9r\u00e9e en tant que recruteur(se) (<a href=\"https:\/\/resources.workable.com\/tutorial\/agency-in-house-recruitment\">recruteur(se) interne<\/a> ou <a href=\"https:\/\/resources.workable.com\/tutorial\/hire-recruiting-agency\">recruteur(se) en agence d'int\u00e9rim<\/a>)<\/li>\r\n \t<li>Excellente capacit\u00e9 \u00e0 r\u00e9aliser diff\u00e9rents types d'entretiens (ex. <a href=\"https:\/\/get.workable.com\/structured-interviews-101\/\" target=\"_blank\" rel=\"noopener noreferrer\">structur\u00e9<\/a>, bas\u00e9 sur les comp\u00e9tences, stress interview)<\/li>\r\n \t<li>Exp\u00e9rience pratique de diff\u00e9rents processus de s\u00e9lection (<a href=\"https:\/\/resources.workable.com\/tutorial\/phone-screen-interview\" target=\"_blank\" rel=\"noopener noreferrer\">entretiens t\u00e9l\u00e9phoniques<\/a>, v\u00e9rification des r\u00e9f\u00e9rences, etc.)<\/li>\r\n \t<li>Capacit\u00e9 \u00e0 organiser les centres d'\u00e9valuation des comp\u00e9tences (ex. activit\u00e9s pratiques, exemples de travaux, tests psychom\u00e9triques et de QI\/QE)<\/li>\r\n \t<li>Familiarit\u00e9 avec les bases de donn\u00e9es RH, les ATS (syst\u00e8mes de suivi des candidats) et les syst\u00e8mes de gestion des candidats (CMS)<\/li>\r\n \t<li>Exp\u00e9rience pratique des logiciels de recrutement, ainsi que des SIRH (syst\u00e8mes d'information des ressources humaines) ou des syst\u00e8mes de gestion des ressources humaines HRMS<\/li>\r\n \t<li>Excellentes comp\u00e9tences de communication et interpersonnelles<\/li>\r\n \t<li>Solides comp\u00e9tences en mati\u00e8re de prise de d\u00e9cision<\/li>\r\n \t<li>Licence\/Master en Gestion des ressources humaines<\/li>\r\n<\/ul>","responsibilities":"<ul>\r\n \t<li>\u00c9laborer et mettre en place la strat\u00e9gie globale de recrutement<\/li>\r\n \t<li>\u00c9laborer et mettre \u00e0 jour les descriptifs et sp\u00e9cifications de postes<\/li>\r\n \t<li>R\u00e9aliser des analyses de poste et de t\u00e2che pour d\u00e9tailler les crit\u00e8res et objectifs des postes<\/li>\r\n \t<li>Pr\u00e9parer les supports de recrutement et publier les annonces sur les sites d'annonces\/journaux\/sites des universit\u00e9s, etc.<\/li>\r\n \t<li>Trouver et recruter des candidats en utilisant les bases de donn\u00e9es, les r\u00e9seaux sociaux, etc.<\/li>\r\n \t<li>Filtrer les CV et candidatures<\/li>\r\n \t<li>R\u00e9aliser les entretiens en utilisant diff\u00e9rents outils\/m\u00e9thodes fiables de recrutement et de s\u00e9lection pour filtrer les candidats dans les d\u00e9lais<\/li>\r\n \t<li>\u00c9valuer les <a href=\"https:\/\/resources.workable.com\/tutorial\/recruiting-skills-training\">connaissances, comp\u00e9tences, comp\u00e9tences personnelles,<\/a>\u00a0exp\u00e9rience et capacit\u00e9s des candidats<\/li>\r\n \t<li>Accueillir les nouveaux employ\u00e9s pour qu'ils s'int\u00e8grent pleinement<\/li>\r\n \t<li>Contr\u00f4ler et appliquer les meilleures pratiques de recrutement RH<\/li>\r\n \t<li>Fournir des rapports de recrutement analytiques et d\u00e9taill\u00e9s au reste de l'\u00e9quipe<\/li>\r\n \t<li>Servir de point de contact et instaurer des relations utiles avec les candidats pendant le processus de s\u00e9lection<\/li>\r\n \t<li>Promouvoir la r\u00e9putation de la soci\u00e9t\u00e9 en tant que \u00ab\u00a0meilleur lieu de travail\u00a0\u00bb<\/li>\r\n<\/ul>","see_more":"<h2>Ressources suppl\u00e9mentaires\u00a0:<\/h2>\r\n<h3>Tutoriels<\/h3>\r\n<ul>\r\n \t<li><a href=\"https:\/\/resources.workable.com\/tutorial\/recruiter-career-success\">Comment \u00eatre un(e) excellent(e) recruteur(se)<\/a><\/li>\r\n \t<li><a href=\"https:\/\/resources.workable.com\/tutorial\/how-to-be-a-successful-recruiter\">Comment \u00eatre un(e) meilleur(e) recruteur(se)<\/a><\/li>\r\n \t<li><a href=\"https:\/\/resources.workable.com\/tutorial\/recruiters-hiring-managers\">Comment travailler plus efficacement avec les responsables de l'embauche<\/a><\/li>\r\n<\/ul>"},"_links":{"self":[{"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/posts\/49382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/comments?post=49382"}],"version-history":[{"count":0,"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/posts\/49382\/revisions"}],"wp:attachment":[{"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/media?parent=49382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/categories?post=49382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resources.workable.com\/fr\/wp-json\/wp\/v2\/tags?post=49382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}