{"id":52437,"date":"2020-01-08T11:08:47","date_gmt":"2020-01-08T11:08:47","guid":{"rendered":"https:\/\/resources.workable.com\/?p=52437"},"modified":"2020-02-06T13:20:30","modified_gmt":"2020-02-06T13:20:30","slug":"descripcion-del-puesto-ejecutivo-de-cuentas-en-publicidad-m-h-x","status":"publish","type":"post","link":"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto","title":{"rendered":"Descripci\u00f3n del puesto: Ejecutivo de cuentas en publicidad&nbsp;(m\/h\/x)"},"content":{"rendered":"<p>Esta plantilla de descripci\u00f3n del puesto de <strong>ejecutivo de cuentas en publicidad<\/strong><span style=\"color: #000000;\"><b>\u00a0<\/b><\/span>est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo o p\u00e1ginas de empleo en Internet y tu empresa podr\u00e1 personalizarla f\u00e1cilmente.<\/p>\n<h2>Responsabilidades del ejecutivo de cuentas en publicidad incluyen:<\/h2>\n<ul>\n<li><span style=\"font-weight: 400;\">Escuchar sugerencias sobre publicidad y los deseos de los clientes, e informar de todo ello a las personas adecuadas de la agencia<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Obtenci\u00f3n de informaci\u00f3n sobre las actividades empresariales y del sector de los clientes para sugerir solucionar m\u00e1s personalizadas<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Colaboraci\u00f3n en eventos promocionales o material publicitario que se adecue a la cuenta y los objetivos de los clientes<\/span><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3922 aligncenter\" src=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2015\/10\/picture-for-ad-acc-ex-640x230.jpg\" alt=\"descripci\u00f3n del puesto de ejecutivo de cuentas en publicidad\" width=\"640\" height=\"230\" srcset=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2015\/10\/picture-for-ad-acc-ex.jpg 640w, https:\/\/resources.workable.com\/wp-content\/uploads\/2015\/10\/picture-for-ad-acc-ex-200x72.jpg 200w, https:\/\/resources.workable.com\/wp-content\/uploads\/2015\/10\/picture-for-ad-acc-ex-560x201.jpg 560w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta plantilla de descripci\u00f3n del puesto de ejecutivo de cuentas en publicidad\u00a0est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo o p\u00e1ginas de empleo en Internet y tu empresa podr\u00e1 personalizarla f\u00e1cilmente. Responsabilidades del ejecutivo de cuentas en publicidad incluyen: Escuchar sugerencias sobre publicidad y los deseos de los clientes, e informar de todo ello [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"no","_lmt_disable":"","_has_post_settings":[],"footnotes":""},"categories":[1046,1305],"tags":[1272],"class_list":["post-52437","post","type-post","status-publish","format-standard","hentry","category-descripciones-de-funciones","category-descripciones-de-puestos-relacionados-con-el-marketing","tag-sample-marketing-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plantilla de descripci\u00f3n del puesto de ejecutivo de cuentas en publicidad | Workable<\/title>\n<meta name=\"description\" content=\"Esta plantilla de descripci\u00f3n del puesto de ejecutivo de cuentas en publicidad est\u00e1 optimizada para las bolsas de trabajo en Internet. Es f\u00e1cil personalizarla con funciones y responsabilidades clave.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plantilla de descripci\u00f3n del puesto de ejecutivo de cuentas en publicidad | Workable\" \/>\n<meta property=\"og:description\" content=\"Esta plantilla de descripci\u00f3n del puesto de ejecutivo de cuentas en publicidad est\u00e1 optimizada para las bolsas de trabajo en Internet. Es f\u00e1cil personalizarla con funciones y responsabilidades clave.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto\" \/>\n<meta property=\"og:site_name\" content=\"Recruiting Resources: How to Recruit and Hire Better\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/workable\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-08T11:08:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-06T13:20:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2015\/10\/picture-for-ad-acc-ex-640x230.jpg\" \/>\n<meta name=\"author\" content=\"Nikoletta Bika\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@workable\" \/>\n<meta name=\"twitter:site\" content=\"@workable\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nikoletta Bika\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto\"},\"author\":{\"name\":\"Nikoletta Bika\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/person\\\/bddaa2e41481e7c9ef2328432ea089e7\"},\"headline\":\"Descripci\u00f3n del puesto: Ejecutivo de cuentas en publicidad&nbsp;(m\\\/h\\\/x)\",\"datePublished\":\"2020-01-08T11:08:47+00:00\",\"dateModified\":\"2020-02-06T13:20:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto\"},\"wordCount\":120,\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/picture-for-ad-acc-ex-640x230.jpg\",\"keywords\":[\"sample-marketing\"],\"articleSection\":[\"Descripciones de funciones\",\"Descripciones de puestos relacionados con el marketing\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto\",\"name\":\"Plantilla de descripci\u00f3n del puesto de ejecutivo de cuentas en publicidad | Workable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/picture-for-ad-acc-ex-640x230.jpg\",\"datePublished\":\"2020-01-08T11:08:47+00:00\",\"dateModified\":\"2020-02-06T13:20:30+00:00\",\"description\":\"Esta plantilla de descripci\u00f3n del puesto de ejecutivo de cuentas en publicidad est\u00e1 optimizada para las bolsas de trabajo en Internet. Es f\u00e1cil personalizarla con funciones y responsabilidades clave.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/resources.workable.com\\\/es\\\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto#primaryimage\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/picture-for-ad-acc-ex-640x230.jpg\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/picture-for-ad-acc-ex-640x230.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descripci\u00f3n del puesto: Ejecutivo de cuentas en publicidad&nbsp;(m\\\/h\\\/x)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/\",\"name\":\"Recruiting Resources: How to Recruit and Hire Better\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#organization\",\"name\":\"Workable\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"width\":150,\"height\":25,\"caption\":\"Workable\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/business.facebook.com\\\/workable\\\/\",\"https:\\\/\\\/x.com\\\/workable\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/workable-hr\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/person\\\/bddaa2e41481e7c9ef2328432ea089e7\",\"name\":\"Nikoletta Bika\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/777bf31309608e9152307199dd8aa97ff19f24849526f1b2b50f11b9ea40fca3?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/777bf31309608e9152307199dd8aa97ff19f24849526f1b2b50f11b9ea40fca3?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/777bf31309608e9152307199dd8aa97ff19f24849526f1b2b50f11b9ea40fca3?s=96&d=mm&r=pg\",\"caption\":\"Nikoletta Bika\"},\"description\":\"Nikoletta Bika was a senior writer at Workable for nearly four and a half years. She holds an MSc in HR and has written extensively about all things HR and recruiting, with a particular interest in bias, data, technology, legal compliance, and the future of work. She hates meaningless jargon and dreams about space travel.\",\"sameAs\":[\"http:\\\/\\\/workable.com\"],\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/author\\\/nikoletta-bika\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plantilla de descripci\u00f3n del puesto de ejecutivo de cuentas en publicidad | Workable","description":"Esta plantilla de descripci\u00f3n del puesto de ejecutivo de cuentas en publicidad est\u00e1 optimizada para las bolsas de trabajo en Internet. Es f\u00e1cil personalizarla con funciones y responsabilidades clave.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto\/","og_locale":"es_ES","og_type":"article","og_title":"Plantilla de descripci\u00f3n del puesto de ejecutivo de cuentas en publicidad | Workable","og_description":"Esta plantilla de descripci\u00f3n del puesto de ejecutivo de cuentas en publicidad est\u00e1 optimizada para las bolsas de trabajo en Internet. Es f\u00e1cil personalizarla con funciones y responsabilidades clave.","og_url":"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto","og_site_name":"Recruiting Resources: How to Recruit and Hire Better","article_publisher":"https:\/\/business.facebook.com\/workable\/","article_published_time":"2020-01-08T11:08:47+00:00","article_modified_time":"2020-02-06T13:20:30+00:00","og_image":[{"url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2015\/10\/picture-for-ad-acc-ex-640x230.jpg","type":"","width":"","height":""}],"author":"Nikoletta Bika","twitter_card":"summary_large_image","twitter_creator":"@workable","twitter_site":"@workable","twitter_misc":{"Escrito por":"Nikoletta Bika","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto#article","isPartOf":{"@id":"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto"},"author":{"name":"Nikoletta Bika","@id":"https:\/\/resources.workable.com\/es\/#\/schema\/person\/bddaa2e41481e7c9ef2328432ea089e7"},"headline":"Descripci\u00f3n del puesto: Ejecutivo de cuentas en publicidad&nbsp;(m\/h\/x)","datePublished":"2020-01-08T11:08:47+00:00","dateModified":"2020-02-06T13:20:30+00:00","mainEntityOfPage":{"@id":"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto"},"wordCount":120,"publisher":{"@id":"https:\/\/resources.workable.com\/es\/#organization"},"image":{"@id":"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2015\/10\/picture-for-ad-acc-ex-640x230.jpg","keywords":["sample-marketing"],"articleSection":["Descripciones de funciones","Descripciones de puestos relacionados con el marketing"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto","url":"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto","name":"Plantilla de descripci\u00f3n del puesto de ejecutivo de cuentas en publicidad | Workable","isPartOf":{"@id":"https:\/\/resources.workable.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto#primaryimage"},"image":{"@id":"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2015\/10\/picture-for-ad-acc-ex-640x230.jpg","datePublished":"2020-01-08T11:08:47+00:00","dateModified":"2020-02-06T13:20:30+00:00","description":"Esta plantilla de descripci\u00f3n del puesto de ejecutivo de cuentas en publicidad est\u00e1 optimizada para las bolsas de trabajo en Internet. Es f\u00e1cil personalizarla con funciones y responsabilidades clave.","breadcrumb":{"@id":"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto#primaryimage","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2015\/10\/picture-for-ad-acc-ex-640x230.jpg","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2015\/10\/picture-for-ad-acc-ex-640x230.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/resources.workable.com\/es\/ejecutivo-de-cuentas-en-publicidad-descripcion-del-puesto#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/resources.workable.com\/es\/"},{"@type":"ListItem","position":2,"name":"Descripci\u00f3n del puesto: Ejecutivo de cuentas en publicidad&nbsp;(m\/h\/x)"}]},{"@type":"WebSite","@id":"https:\/\/resources.workable.com\/es\/#website","url":"https:\/\/resources.workable.com\/es\/","name":"Recruiting Resources: How to Recruit and Hire Better","description":"","publisher":{"@id":"https:\/\/resources.workable.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/resources.workable.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/resources.workable.com\/es\/#organization","name":"Workable","url":"https:\/\/resources.workable.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/resources.workable.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","width":150,"height":25,"caption":"Workable"},"image":{"@id":"https:\/\/resources.workable.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/workable\/","https:\/\/x.com\/workable","https:\/\/www.linkedin.com\/company\/workable-hr\/"]},{"@type":"Person","@id":"https:\/\/resources.workable.com\/es\/#\/schema\/person\/bddaa2e41481e7c9ef2328432ea089e7","name":"Nikoletta Bika","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/777bf31309608e9152307199dd8aa97ff19f24849526f1b2b50f11b9ea40fca3?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/777bf31309608e9152307199dd8aa97ff19f24849526f1b2b50f11b9ea40fca3?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/777bf31309608e9152307199dd8aa97ff19f24849526f1b2b50f11b9ea40fca3?s=96&d=mm&r=pg","caption":"Nikoletta Bika"},"description":"Nikoletta Bika was a senior writer at Workable for nearly four and a half years. She holds an MSc in HR and has written extensively about all things HR and recruiting, with a particular interest in bias, data, technology, legal compliance, and the future of work. She hates meaningless jargon and dreams about space travel.","sameAs":["http:\/\/workable.com"],"url":"https:\/\/resources.workable.com\/es\/author\/nikoletta-bika\/"}]}},"modified_by":"Alexandra Marinaki","custom_fields":{"brief":"<span style=\"font-weight: 400;\">Buscamos un <strong>ejecutivo de cuentas en publicidad<\/strong> cualificado para gestionar cuentas de clientes y actuar de enlace entre ellos y nuestra agencia. Ser\u00e1s el contacto clave de los clientes que se te asignen.<\/span> <span style=\"font-weight: 400;\">Tu trabajo ser\u00e1 vital para mantener la satisfacci\u00f3n del cliente, para lo cu\u00e1l tendr\u00e1s que escuchar sus preferencias y atenderles con un asesoramiento y unos servicios eficaces. El candidato ideal ha de ser una persona que sepa escuchar y tener un enfoque orientado al cliente.<\/span> <span style=\"font-weight: 400;\">La meta es asegurarse de desarrollar continuamente nuestras actividades empresariales y consolidar nuestra agencia como uno de los l\u00edderes del sector.<\/span>","requirements":"<ul>\r\n \t<li><span style=\"font-weight: 400;\">Experiencia demostrable como ejecutivo de cuentas en publicidad o un puesto similar<\/span><\/li>\r\n \t<li><span style=\"font-weight: 400;\">Buenos conocimientos de marketing as\u00ed como m\u00e9todos y t\u00e9cnicas de publicidad<\/span><\/li>\r\n \t<li><span style=\"font-weight: 400;\">Buenos conocimientos de MS Office; se valorar\u00e1n conocimientos pr\u00e1cticos de software CRM<\/span><\/li>\r\n \t<li><span style=\"font-weight: 400;\">Capacidad para afrontar m\u00faltiples tareas y gestionar una gran variedad de cuentas posiblemente pertenecientes a diferentes sectores<\/span><\/li>\r\n \t<li><span style=\"font-weight: 400;\">Buen trabajador en equipo y excelentes habilidades para las comunicaciones y las presentaciones<\/span><\/li>\r\n \t<li><span style=\"font-weight: 400;\">Grado en Administraci\u00f3n de Empresas, Marketing o un campo relacionado<\/span><\/li>\r\n<\/ul>","responsibilities":"<ul>\r\n \t<li><span style=\"font-weight: 400;\">Mantener una comunicaci\u00f3n fluida con clientes para entender sus necesidades y especificaciones<\/span><\/li>\r\n \t<li><span style=\"font-weight: 400;\">Escuchar sugerencias sobre publicidad y los deseos de los clientes, e informar de todo ello a las personas adecuadas de la agencia<\/span><\/li>\r\n \t<li><span style=\"font-weight: 400;\">Obtener informaci\u00f3n sobre las actividades empresariales y del sector de los clientes para sugerir solucionar m\u00e1s personalizadas<\/span><\/li>\r\n \t<li><span style=\"font-weight: 400;\">Coordinarse con clientes para organizar eventos promocionales o decidir el material publicitario que mejor se adapta a sus perfiles y objetivos<\/span><\/li>\r\n \t<li><span style=\"font-weight: 400;\">Colaborar con compa\u00f1eros para dise\u00f1ar campa\u00f1as creativas y otros proyectos de acuerdo con los est\u00e1ndares acordados con los clientes<\/span><\/li>\r\n \t<li><span style=\"font-weight: 400;\">Emplear t\u00e9cnicas para crear redes con el fin de atraer nuevos clientes<\/span><\/li>\r\n \t<li><span style=\"font-weight: 400;\">Negociar presupuestos y plazos, y realizar presentaciones detalladas que justifiquen los costes y calendarios<\/span><\/li>\r\n \t<li><span style=\"font-weight: 400;\">Ocuparse de tareas administrativas y llevar un registro de los clientes<\/span><\/li>\r\n<\/ul>","see_more":""},"_links":{"self":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/posts\/52437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/comments?post=52437"}],"version-history":[{"count":0,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/posts\/52437\/revisions"}],"wp:attachment":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/media?parent=52437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/categories?post=52437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/tags?post=52437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}