{"id":45344,"date":"2020-01-08T11:06:13","date_gmt":"2020-01-08T11:06:13","guid":{"rendered":"https:\/\/resources.workable.com\/?p=45344"},"modified":"2020-02-06T13:16:15","modified_gmt":"2020-02-06T13:16:15","slug":"descripcion-del-puesto-ingeniero-de-pruebas-m-h-x","status":"publish","type":"post","link":"https:\/\/resources.workable.com\/es\/ingeniero-de-pruebas-descripcion-del-puesto","title":{"rendered":"Descripci\u00f3n del puesto: Ingeniero de pruebas&nbsp;(m\/h\/x)"},"content":{"rendered":"<p>Usa esta plantilla de descripci\u00f3n del puesto de ingeniero de pruebas para contratar a empleados cualificados para tu empresa de fabricaci\u00f3n, zona de construcci\u00f3n o f\u00e1brica. Puedes personalizar los deberes y requisitos seg\u00fan tus necesidades. Para los puestos relacionados con el desarrollo de software, consulta nuestra <a href=\"https:\/\/resources.workable.com\/qa-tester-job-description\" target=\"_blank\" rel=\"noopener noreferrer\">descripci\u00f3n del puesto de ingeniero de pruebas en control de calidad<\/a>.<\/p>\n<h2>\u00bfQu\u00e9 es un ingeniero de pruebas?<\/h2>\n<p>Los t\u00e9cnicos de pruebas inspeccionan e informan sobre la calidad de los productos a lo largo de todo el ciclo de producci\u00f3n. En funci\u00f3n del producto, pueden utilizar diferentes criterios para comprobar la calidad como la funcionalidad, la durabilidad, la seguridad y la velocidad.<\/p>\n<h2>\u00bfQu\u00e9 hace un ingeniero de pruebas?<\/h2>\n<p>La funci\u00f3n de los ingenieros de pruebas consiste en comprobar minuciosamente los materiales, procedimientos y sistemas el\u00e9ctricos o mec\u00e1nicos para garantizar que los clientes obtengan productos funcionales de alta calidad. Ejecutan pruebas en diversos componentes y funciones para detectar y reparar problemas t\u00e9cnicos. Los ingenieros de pruebas con experiencia pueden adem\u00e1s encargarse de la formaci\u00f3n y gesti\u00f3n de miembros del equipo junior.<\/p>\n<h2>Entre las responsabilidades del t\u00e9cnico de pruebas se incluyen:<\/h2>\n<ul>\n<li>Inspecci\u00f3n de materias primas y maquinaria<\/li>\n<li>Creaci\u00f3n de entornos de pruebas<\/li>\n<li>An\u00e1lisis de resultados y detecci\u00f3n de las causas que originan los fallos<\/li>\n<\/ul>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Usa esta plantilla de descripci\u00f3n del puesto de ingeniero de pruebas para contratar a empleados cualificados para tu empresa de fabricaci\u00f3n, zona de construcci\u00f3n o f\u00e1brica. Puedes personalizar los deberes y requisitos seg\u00fan tus necesidades. Para los puestos relacionados con el desarrollo de software, consulta nuestra descripci\u00f3n del puesto de ingeniero de pruebas en control [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"no","_lmt_disable":"","_has_post_settings":[],"footnotes":""},"categories":[1046,1240],"tags":[],"class_list":["post-45344","post","type-post","status-publish","format-standard","hentry","category-descripciones-de-funciones","category-descripciones-de-puestos-de-construccion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Descripci\u00f3n del puesto: Ingeniero de pruebas (m\/h\/x) exemple - Workable<\/title>\n<meta name=\"description\" content=\"Usa esta plantilla de descripci\u00f3n del puesto de ingeniero de pruebas para contratar a empleados cualificados para tu empresa de fabricaci\u00f3n, zona de construcci\u00f3n o f\u00e1brica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/resources.workable.com\/es\/ingeniero-de-pruebas-descripcion-del-puesto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descripci\u00f3n del puesto: Ingeniero de pruebas (m\/h\/x) exemple - Workable\" \/>\n<meta property=\"og:description\" content=\"Usa esta plantilla de descripci\u00f3n del puesto de ingeniero de pruebas para contratar a empleados cualificados para tu empresa de fabricaci\u00f3n, zona de construcci\u00f3n o f\u00e1brica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/resources.workable.com\/es\/ingeniero-de-pruebas-descripcion-del-puesto\" \/>\n<meta property=\"og:site_name\" content=\"Recruiting Resources: How to Recruit and Hire Better\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/workable\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-08T11:06:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-06T13:16:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2024\/02\/workable_thumb.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Christina Pavlou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@workable\" \/>\n<meta name=\"twitter:site\" content=\"@workable\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina Pavlou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-pruebas-descripcion-del-puesto#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-pruebas-descripcion-del-puesto\"},\"author\":{\"name\":\"Christina Pavlou\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/person\\\/b23289d8d63331621eee9e69103cd603\"},\"headline\":\"Descripci\u00f3n del puesto: Ingeniero de pruebas&nbsp;(m\\\/h\\\/x)\",\"datePublished\":\"2020-01-08T11:06:13+00:00\",\"dateModified\":\"2020-02-06T13:16:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-pruebas-descripcion-del-puesto\"},\"wordCount\":238,\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#organization\"},\"articleSection\":[\"Descripciones de funciones\",\"Descripciones de puestos de construcci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-pruebas-descripcion-del-puesto\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-pruebas-descripcion-del-puesto\",\"name\":\"Descripci\u00f3n del puesto: Ingeniero de pruebas (m\\\/h\\\/x) exemple - Workable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#website\"},\"datePublished\":\"2020-01-08T11:06:13+00:00\",\"dateModified\":\"2020-02-06T13:16:15+00:00\",\"description\":\"Usa esta plantilla de descripci\u00f3n del puesto de ingeniero de pruebas para contratar a empleados cualificados para tu empresa de fabricaci\u00f3n, zona de construcci\u00f3n o f\u00e1brica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-pruebas-descripcion-del-puesto#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-pruebas-descripcion-del-puesto\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-pruebas-descripcion-del-puesto#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descripci\u00f3n del puesto: Ingeniero de pruebas&nbsp;(m\\\/h\\\/x)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/\",\"name\":\"Recruiting Resources: How to Recruit and Hire Better\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#organization\",\"name\":\"Workable\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"width\":150,\"height\":25,\"caption\":\"Workable\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/business.facebook.com\\\/workable\\\/\",\"https:\\\/\\\/x.com\\\/workable\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/workable-hr\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/person\\\/b23289d8d63331621eee9e69103cd603\",\"name\":\"Christina Pavlou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg\",\"caption\":\"Christina Pavlou\"},\"description\":\"Christina Pavlou was a writer at Workable for nearly four years, and previously a recruiter. She writes about diversity in the workplace and reports on the shape of things to come. You can find her on LinkedIn and Twitter.\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/author\\\/christina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descripci\u00f3n del puesto: Ingeniero de pruebas (m\/h\/x) exemple - Workable","description":"Usa esta plantilla de descripci\u00f3n del puesto de ingeniero de pruebas para contratar a empleados cualificados para tu empresa de fabricaci\u00f3n, zona de construcci\u00f3n o f\u00e1brica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/resources.workable.com\/es\/ingeniero-de-pruebas-descripcion-del-puesto\/","og_locale":"es_ES","og_type":"article","og_title":"Descripci\u00f3n del puesto: Ingeniero de pruebas (m\/h\/x) exemple - Workable","og_description":"Usa esta plantilla de descripci\u00f3n del puesto de ingeniero de pruebas para contratar a empleados cualificados para tu empresa de fabricaci\u00f3n, zona de construcci\u00f3n o f\u00e1brica.","og_url":"https:\/\/resources.workable.com\/es\/ingeniero-de-pruebas-descripcion-del-puesto","og_site_name":"Recruiting Resources: How to Recruit and Hire Better","article_publisher":"https:\/\/business.facebook.com\/workable\/","article_published_time":"2020-01-08T11:06:13+00:00","article_modified_time":"2020-02-06T13:16:15+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2024\/02\/workable_thumb.png","type":"image\/png"}],"author":"Christina Pavlou","twitter_card":"summary_large_image","twitter_creator":"@workable","twitter_site":"@workable","twitter_misc":{"Escrito por":"Christina Pavlou","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-pruebas-descripcion-del-puesto#article","isPartOf":{"@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-pruebas-descripcion-del-puesto"},"author":{"name":"Christina Pavlou","@id":"https:\/\/resources.workable.com\/es\/#\/schema\/person\/b23289d8d63331621eee9e69103cd603"},"headline":"Descripci\u00f3n del puesto: Ingeniero de pruebas&nbsp;(m\/h\/x)","datePublished":"2020-01-08T11:06:13+00:00","dateModified":"2020-02-06T13:16:15+00:00","mainEntityOfPage":{"@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-pruebas-descripcion-del-puesto"},"wordCount":238,"publisher":{"@id":"https:\/\/resources.workable.com\/es\/#organization"},"articleSection":["Descripciones de funciones","Descripciones de puestos de construcci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-pruebas-descripcion-del-puesto","url":"https:\/\/resources.workable.com\/es\/ingeniero-de-pruebas-descripcion-del-puesto","name":"Descripci\u00f3n del puesto: Ingeniero de pruebas (m\/h\/x) exemple - Workable","isPartOf":{"@id":"https:\/\/resources.workable.com\/es\/#website"},"datePublished":"2020-01-08T11:06:13+00:00","dateModified":"2020-02-06T13:16:15+00:00","description":"Usa esta plantilla de descripci\u00f3n del puesto de ingeniero de pruebas para contratar a empleados cualificados para tu empresa de fabricaci\u00f3n, zona de construcci\u00f3n o f\u00e1brica.","breadcrumb":{"@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-pruebas-descripcion-del-puesto#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/resources.workable.com\/es\/ingeniero-de-pruebas-descripcion-del-puesto"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-pruebas-descripcion-del-puesto#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/resources.workable.com\/es\/"},{"@type":"ListItem","position":2,"name":"Descripci\u00f3n del puesto: Ingeniero de pruebas&nbsp;(m\/h\/x)"}]},{"@type":"WebSite","@id":"https:\/\/resources.workable.com\/es\/#website","url":"https:\/\/resources.workable.com\/es\/","name":"Recruiting Resources: How to Recruit and Hire Better","description":"","publisher":{"@id":"https:\/\/resources.workable.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/resources.workable.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/resources.workable.com\/es\/#organization","name":"Workable","url":"https:\/\/resources.workable.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/resources.workable.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","width":150,"height":25,"caption":"Workable"},"image":{"@id":"https:\/\/resources.workable.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/workable\/","https:\/\/x.com\/workable","https:\/\/www.linkedin.com\/company\/workable-hr\/"]},{"@type":"Person","@id":"https:\/\/resources.workable.com\/es\/#\/schema\/person\/b23289d8d63331621eee9e69103cd603","name":"Christina Pavlou","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg","caption":"Christina Pavlou"},"description":"Christina Pavlou was a writer at Workable for nearly four years, and previously a recruiter. She writes about diversity in the workplace and reports on the shape of things to come. You can find her on LinkedIn and Twitter.","url":"https:\/\/resources.workable.com\/es\/author\/christina\/"}]}},"modified_by":"Nikoletta Bika","custom_fields":{"brief":"Buscamos un t\u00e9cnico de pruebas que inspeccione minuciosamente nuestros productos antes de introducirlos en el mercado.\r\n\r\nComo t\u00e9cnico de pruebas de nuestra empresa, trabajar\u00e1s codo con codo con el equipo de producci\u00f3n para comprender por qu\u00e9 creamos un producto y cu\u00e1les son sus requisitos espec\u00edficos. A continuaci\u00f3n, ejecutar\u00e1s una serie de pruebas a lo largo de todas las fases de producci\u00f3n para detectar posibles fallos y recomendar mejoras.\r\n\r\nEn \u00faltima instancia, garantizar\u00e1s que nuestros productos finales cumplan nuestras normas de seguridad y calidad.\r\n<div><\/div>","requirements":"<ul>\r\n \t<li>Experiencia anterior como ingeniero de pruebas o en un puesto similar<\/li>\r\n \t<li>Familiaridad con diversas t\u00e9cnicas de pruebas<\/li>\r\n \t<li>Experiencia pr\u00e1ctica con sistemas de gesti\u00f3n de calidad (SGC)<\/li>\r\n \t<li>Conocimiento de las normas y los est\u00e1ndares de calidad<\/li>\r\n \t<li>Excelentes habilidades para solucionar problemas<\/li>\r\n \t<li>Mentalidad anal\u00edtica<\/li>\r\n \t<li>Grado en Ingenier\u00eda Mec\u00e1nica, Ingenier\u00eda Industrial o campo relacionado<\/li>\r\n \t<li>Se valorar\u00e1 estar en posesi\u00f3n de un titulo adicional en control de calidad<\/li>\r\n<\/ul>\r\n<div><\/div>","responsibilities":"<ul>\r\n \t<li>Recopilar requisitos de productos (p. ej., funcionalidades, velocidad y normas de seguridad)<\/li>\r\n \t<li>Inspeccionar las materias primas y la maquinaria para detectar defectos y fallos<\/li>\r\n \t<li>Supervisar todas las fases de producci\u00f3n para garantizar que se sigan los procedimientos de seguridad<\/li>\r\n \t<li>Ejecutar controles de calidad de los componentes y productos finales<\/li>\r\n \t<li>Desarrollar pruebas medioambientales y casos experimentales para todos los sistemas el\u00e9ctricos y mec\u00e1nicos<\/li>\r\n \t<li>Analizar los resultados de las pruebas, detectar problemas y buscar las causas que los originan<\/li>\r\n \t<li>Proponer correcciones y mejoras<\/li>\r\n \t<li>Documentar los problemas t\u00e9cnicos y soluciones<\/li>\r\n \t<li>Crear sistemas de pruebas automatizadas para comprobaciones peri\u00f3dicas<\/li>\r\n \t<li>Garantizar que nuestros productos y procedimientos cumplen los est\u00e1ndares de la industrial (p. ej., ISO)<\/li>\r\n<\/ul>\r\n<div><\/div>","see_more":"<h3>Recursos pertinentes:<\/h3>\r\n<ul>\r\n \t<li><a href=\"https:\/\/resources.workable.com\/quality-engineer-job-description\" target=\"_blank\" rel=\"noopener\">Descripci\u00f3n del puesto de ingeniero de calidad<\/a><\/li>\r\n \t<li><a href=\"https:\/\/resources.workable.com\/quality-manager-job-description\" target=\"_blank\" rel=\"noopener\">Descripci\u00f3n del puesto de gerente de calidad<\/a><\/li>\r\n \t<li><a href=\"https:\/\/resources.workable.com\/production-manager-job-description\" target=\"_blank\" rel=\"noopener\">Descripci\u00f3n del puesto de gerente de producci\u00f3n<\/a><\/li>\r\n<\/ul>\r\n<div><\/div>"},"_links":{"self":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/posts\/45344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/comments?post=45344"}],"version-history":[{"count":0,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/posts\/45344\/revisions"}],"wp:attachment":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/media?parent=45344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/categories?post=45344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/tags?post=45344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}