{"id":42855,"date":"2020-01-08T11:05:28","date_gmt":"2020-01-08T11:05:28","guid":{"rendered":"https:\/\/resources.workable.com\/?p=42855"},"modified":"2020-02-06T13:21:41","modified_gmt":"2020-02-06T13:21:41","slug":"descripcion-del-puesto-especialista-en-soporte-tecnico-m-h-x","status":"publish","type":"post","link":"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto","title":{"rendered":"Descripci\u00f3n del puesto: Especialista en soporte t\u00e9cnico&nbsp;(m\/h\/x)"},"content":{"rendered":"<p>Esta plantilla de descripci\u00f3n del puesto de<strong> especialista en soporte t\u00e9cnico<\/strong>\u00a0 est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet , y tu empresa podr\u00e1 personalizarla f\u00e1cilmente. Otros puestos similares ser\u00edan los de <a href=\"https:\/\/resources.workable.com\/customer-service-representative-job-description\">representante del servicio de atenci\u00f3n al cliente<\/a>\u00a0e\u00a0<a href=\"https:\/\/resources.workable.com\/technical-support-engineer-job-description\">ingeniero de soporte t\u00e9cnico<\/a>.<\/p>\n<h2>Responsabilidades de un especialista en soporte t\u00e9cnico incluyen:<\/h2>\n<ul>\n<li>Proporcionar el contacto de primer nivel y soluciones a problemas t\u00e9cnicos de los clientes<\/li>\n<li>Derivar adecuadamente las consultas sin resolver a la siguiente nivel de soporte<\/li>\n<li>Hacer un seguimiento, encaminar y redirigir problemas a los recursos adecuados<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3425 aligncenter\" src=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/help-desk-specialist-640x230.jpg\" alt=\"descripci\u00f3n del puesto de especialista en soporte t\u00e9cnico\" width=\"640\" height=\"230\" srcset=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/help-desk-specialist.jpg 640w, https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/help-desk-specialist-200x72.jpg 200w, https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/help-desk-specialist-560x201.jpg 560w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta plantilla de descripci\u00f3n del puesto de especialista en soporte t\u00e9cnico\u00a0 est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet , y tu empresa podr\u00e1 personalizarla f\u00e1cilmente. Otros puestos similares ser\u00edan los de representante del servicio de atenci\u00f3n al cliente\u00a0e\u00a0ingeniero de soporte t\u00e9cnico. Responsabilidades de un especialista en soporte [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"no","_lmt_disable":"","_has_post_settings":[],"footnotes":""},"categories":[1046,1196],"tags":[1195],"class_list":["post-42855","post","type-post","status-publish","format-standard","hentry","category-descripciones-de-funciones","category-descripciones-de-puestos-de-atencion-al-cliente","tag-sample-customer-service-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plantilla de descripci\u00f3n del puesto de especialista en soporte t\u00e9cnico | Workable<\/title>\n<meta name=\"description\" content=\"Esta plantilla de descripci\u00f3n del puesto de especialista en soporte t\u00e9cnico est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet , y tu empresa podr\u00e1 personalizarla f\u00e1cilmente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plantilla de descripci\u00f3n del puesto de especialista en soporte t\u00e9cnico | Workable\" \/>\n<meta property=\"og:description\" content=\"Esta plantilla de descripci\u00f3n del puesto de especialista en soporte t\u00e9cnico est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet , y tu empresa podr\u00e1 personalizarla f\u00e1cilmente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto\" \/>\n<meta property=\"og:site_name\" content=\"Recruiting Resources: How to Recruit and Hire Better\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/workable\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-08T11:05:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-06T13:21:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/help-desk-specialist-640x230.jpg\" \/>\n<meta name=\"author\" content=\"Eleni Kourmentza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@workable\" \/>\n<meta name=\"twitter:site\" content=\"@workable\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eleni Kourmentza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/especialista-en-soporte-tecnico-descripcion-del-puesto#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/especialista-en-soporte-tecnico-descripcion-del-puesto\"},\"author\":{\"name\":\"Eleni Kourmentza\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/person\\\/246aec99718ddcb172f71f699e088a88\"},\"headline\":\"Descripci\u00f3n del puesto: Especialista en soporte t\u00e9cnico&nbsp;(m\\\/h\\\/x)\",\"datePublished\":\"2020-01-08T11:05:28+00:00\",\"dateModified\":\"2020-02-06T13:21:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/especialista-en-soporte-tecnico-descripcion-del-puesto\"},\"wordCount\":117,\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/especialista-en-soporte-tecnico-descripcion-del-puesto#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/help-desk-specialist-640x230.jpg\",\"keywords\":[\"sample-customer-service\"],\"articleSection\":[\"Descripciones de funciones\",\"Descripciones de puestos de atenci\u00f3n al cliente\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/especialista-en-soporte-tecnico-descripcion-del-puesto\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/especialista-en-soporte-tecnico-descripcion-del-puesto\",\"name\":\"Plantilla de descripci\u00f3n del puesto de especialista en soporte t\u00e9cnico | Workable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/especialista-en-soporte-tecnico-descripcion-del-puesto#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/especialista-en-soporte-tecnico-descripcion-del-puesto#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/help-desk-specialist-640x230.jpg\",\"datePublished\":\"2020-01-08T11:05:28+00:00\",\"dateModified\":\"2020-02-06T13:21:41+00:00\",\"description\":\"Esta plantilla de descripci\u00f3n del puesto de especialista en soporte t\u00e9cnico est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet , y tu empresa podr\u00e1 personalizarla f\u00e1cilmente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/especialista-en-soporte-tecnico-descripcion-del-puesto#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/resources.workable.com\\\/es\\\/especialista-en-soporte-tecnico-descripcion-del-puesto\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/especialista-en-soporte-tecnico-descripcion-del-puesto#primaryimage\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/help-desk-specialist-640x230.jpg\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/help-desk-specialist-640x230.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/especialista-en-soporte-tecnico-descripcion-del-puesto#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descripci\u00f3n del puesto: Especialista en soporte t\u00e9cnico&nbsp;(m\\\/h\\\/x)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/\",\"name\":\"Recruiting Resources: How to Recruit and Hire Better\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#organization\",\"name\":\"Workable\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"width\":150,\"height\":25,\"caption\":\"Workable\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/business.facebook.com\\\/workable\\\/\",\"https:\\\/\\\/x.com\\\/workable\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/workable-hr\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/person\\\/246aec99718ddcb172f71f699e088a88\",\"name\":\"Eleni Kourmentza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg\",\"caption\":\"Eleni Kourmentza\"},\"description\":\"Eleni Kourmentza, ex-People Ops Manager at Workable, excelled in recruitment, lifecycle management, HR admin, culture nurturing, and employer branding.\",\"sameAs\":[\"http:\\\/\\\/workable.com\"],\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/author\\\/eleni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plantilla de descripci\u00f3n del puesto de especialista en soporte t\u00e9cnico | Workable","description":"Esta plantilla de descripci\u00f3n del puesto de especialista en soporte t\u00e9cnico est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet , y tu empresa podr\u00e1 personalizarla f\u00e1cilmente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto\/","og_locale":"es_ES","og_type":"article","og_title":"Plantilla de descripci\u00f3n del puesto de especialista en soporte t\u00e9cnico | Workable","og_description":"Esta plantilla de descripci\u00f3n del puesto de especialista en soporte t\u00e9cnico est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet , y tu empresa podr\u00e1 personalizarla f\u00e1cilmente.","og_url":"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto","og_site_name":"Recruiting Resources: How to Recruit and Hire Better","article_publisher":"https:\/\/business.facebook.com\/workable\/","article_published_time":"2020-01-08T11:05:28+00:00","article_modified_time":"2020-02-06T13:21:41+00:00","og_image":[{"url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/help-desk-specialist-640x230.jpg","type":"","width":"","height":""}],"author":"Eleni Kourmentza","twitter_card":"summary_large_image","twitter_creator":"@workable","twitter_site":"@workable","twitter_misc":{"Escrito por":"Eleni Kourmentza","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto#article","isPartOf":{"@id":"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto"},"author":{"name":"Eleni Kourmentza","@id":"https:\/\/resources.workable.com\/es\/#\/schema\/person\/246aec99718ddcb172f71f699e088a88"},"headline":"Descripci\u00f3n del puesto: Especialista en soporte t\u00e9cnico&nbsp;(m\/h\/x)","datePublished":"2020-01-08T11:05:28+00:00","dateModified":"2020-02-06T13:21:41+00:00","mainEntityOfPage":{"@id":"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto"},"wordCount":117,"publisher":{"@id":"https:\/\/resources.workable.com\/es\/#organization"},"image":{"@id":"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/help-desk-specialist-640x230.jpg","keywords":["sample-customer-service"],"articleSection":["Descripciones de funciones","Descripciones de puestos de atenci\u00f3n al cliente"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto","url":"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto","name":"Plantilla de descripci\u00f3n del puesto de especialista en soporte t\u00e9cnico | Workable","isPartOf":{"@id":"https:\/\/resources.workable.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto#primaryimage"},"image":{"@id":"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/help-desk-specialist-640x230.jpg","datePublished":"2020-01-08T11:05:28+00:00","dateModified":"2020-02-06T13:21:41+00:00","description":"Esta plantilla de descripci\u00f3n del puesto de especialista en soporte t\u00e9cnico est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet , y tu empresa podr\u00e1 personalizarla f\u00e1cilmente.","breadcrumb":{"@id":"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto#primaryimage","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/help-desk-specialist-640x230.jpg","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/help-desk-specialist-640x230.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/resources.workable.com\/es\/especialista-en-soporte-tecnico-descripcion-del-puesto#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/resources.workable.com\/es\/"},{"@type":"ListItem","position":2,"name":"Descripci\u00f3n del puesto: Especialista en soporte t\u00e9cnico&nbsp;(m\/h\/x)"}]},{"@type":"WebSite","@id":"https:\/\/resources.workable.com\/es\/#website","url":"https:\/\/resources.workable.com\/es\/","name":"Recruiting Resources: How to Recruit and Hire Better","description":"","publisher":{"@id":"https:\/\/resources.workable.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/resources.workable.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/resources.workable.com\/es\/#organization","name":"Workable","url":"https:\/\/resources.workable.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/resources.workable.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","width":150,"height":25,"caption":"Workable"},"image":{"@id":"https:\/\/resources.workable.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/workable\/","https:\/\/x.com\/workable","https:\/\/www.linkedin.com\/company\/workable-hr\/"]},{"@type":"Person","@id":"https:\/\/resources.workable.com\/es\/#\/schema\/person\/246aec99718ddcb172f71f699e088a88","name":"Eleni Kourmentza","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg","caption":"Eleni Kourmentza"},"description":"Eleni Kourmentza, ex-People Ops Manager at Workable, excelled in recruitment, lifecycle management, HR admin, culture nurturing, and employer branding.","sameAs":["http:\/\/workable.com"],"url":"https:\/\/resources.workable.com\/es\/author\/eleni\/"}]}},"modified_by":"Alexandra Marinaki","custom_fields":{"brief":"<p dir=\"ltr\">Buscamos a un especialista en soporte t\u00e9cnico orientado a la atenci\u00f3n al cliente para proporcionar soporte t\u00e9cnico a usuarios de forma eficiente y precisa. Se te considerar\u00e1 el primer punto de contacto de la empresa y resolver\u00e1s problemas t\u00e9cnicos b\u00e1sicos, adem\u00e1s de ofrecer soporte en todas las \u00e1reas asignadas. El objetivo es asegurar que se mantiene el valor que aportamos al cliente con la calidad establecida por la empresa.<\/p>","requirements":"<ul>\r\n \t<li>Experiencia laboral demostrable en proporcionar soporte t\u00e9cnico<\/li>\r\n \t<li>Dominio del ingl\u00e9s<\/li>\r\n \t<li>Conocimientos pr\u00e1cticos de software de soporte, bases de datos y control remoto<\/li>\r\n \t<li>Grandes capacidades para la atenci\u00f3n al cliente y la comunicaci\u00f3n<\/li>\r\n \t<li>Avanzadas capacidades para solucionar problemas y para realizar varias tareas a la vez<\/li>\r\n \t<li>Orientaci\u00f3n a la atenci\u00f3n al cliente<\/li>\r\n \t<li>Grado en Tecnolog\u00eda de la Informaci\u00f3n, Inform\u00e1tica o una materia equivalente<\/li>\r\n<\/ul>","responsibilities":"<ul>\r\n \t<li>Proporcionar el contacto de primer nivel y soluciones a problemas t\u00e9cnicos de los clientes<\/li>\r\n \t<li>Derivar adecuadamente las consultas sin resolver al siguiente nivel de soporte<\/li>\r\n \t<li>Hacer un seguimiento, encaminar y redirigir problemas a los recursos adecuados<\/li>\r\n \t<li>Actualizar datos de clientes y elaborar informes de actividad<\/li>\r\n \t<li>Guiar a los clientes por el proceso de resoluci\u00f3n del problema<\/li>\r\n \t<li>Har\u00e1s un seguimiento de los clientes, proporcionar\u00e1s respuestas y comentarios y te har\u00e1s cargo de los problemas hasta la soluci\u00f3n<\/li>\r\n \t<li>Utilizar\u00e1s excelentes capacidades de atenci\u00f3n al cliente y superar\u00e1s las expectativas de los clientes<\/li>\r\n \t<li>Garantizar el adecuado registro, documentaci\u00f3n y cierre<\/li>\r\n \t<li>Recomendar modificaciones y mejoras de procesos<\/li>\r\n \t<li>Preservar y desarrollar tus conocimientos sobre procedimientos de soporte, productos y servicios<\/li>\r\n<\/ul>","see_more":""},"_links":{"self":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/posts\/42855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/comments?post=42855"}],"version-history":[{"count":0,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/posts\/42855\/revisions"}],"wp:attachment":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/media?parent=42855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/categories?post=42855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/tags?post=42855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}