{"id":40873,"date":"2020-01-08T11:04:52","date_gmt":"2020-01-08T11:04:52","guid":{"rendered":"https:\/\/resources.workable.com\/?p=40873"},"modified":"2020-02-06T13:23:00","modified_gmt":"2020-02-06T13:23:00","slug":"descripcion-del-puesto-ingeniero-de-seguridad-de-software-m-h-x","status":"publish","type":"post","link":"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto","title":{"rendered":"Descripci\u00f3n del puesto: Ingeniero de seguridad de software&nbsp;(m\/h\/x)"},"content":{"rendered":"<p>Esta plantilla de descripci\u00f3n del puesto de <strong>ingeniero de seguridad de software<\/strong> est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet, y tu empresa podr\u00e1 personalizarla f\u00e1cilmente. \u00a0Otro puesto similar ser\u00eda el de <a href=\"https:\/\/resources.workable.com\/software-engineer-job-description\">ingeniero de software<\/a>.<\/p>\n<h2>Responsabilidades del ingeniero de seguridad de software incluyen:<\/h2>\n<ul>\n<li>Implementar, probar y utilizar avanzadas t\u00e9cnicas de seguridad de software de acuerdo con la arquitectura de referencia t\u00e9cnica<\/li>\n<li>Realizar pruebas continuas de seguridad y revisar el c\u00f3digo para mejorar la seguridad del software<\/li>\n<li>Solucionar y depurar los problemas que surjan<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3400 aligncenter\" src=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/software-security-engineer-640x230.jpg\" alt=\"descripci\u00f3n del puesto de ingeniero de seguridad de software\" width=\"640\" height=\"230\" srcset=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/software-security-engineer.jpg 640w, https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/software-security-engineer-200x72.jpg 200w, https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/software-security-engineer-560x201.jpg 560w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><a href=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/sofware-security-engineer-job-description.jpg\"><br \/>\n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta plantilla de descripci\u00f3n del puesto de ingeniero de seguridad de software est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet, y tu empresa podr\u00e1 personalizarla f\u00e1cilmente. \u00a0Otro puesto similar ser\u00eda el de ingeniero de software. Responsabilidades del ingeniero de seguridad de software incluyen: Implementar, probar y utilizar avanzadas [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"no","_lmt_disable":"","_has_post_settings":[],"footnotes":""},"categories":[1046,1047],"tags":[1176],"class_list":["post-40873","post","type-post","status-publish","format-standard","hentry","category-descripciones-de-funciones","category-descripciones-de-funciones-de-puestos-de-ti-y-desarrollo","tag-informatica-muestra"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Plantilla de descripci\u00f3n del puesto de ingeniero de seguridad de software | Workable<\/title>\n<meta name=\"description\" content=\"Esta plantilla de descripci\u00f3n del puesto de ingeniero de seguridad de software est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet, y se podr\u00e1 personalizar f\u00e1cilmente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descripci\u00f3n del puesto: Ingeniero de seguridad de software (m\/h\/x)\" \/>\n<meta property=\"og:description\" content=\"Esta plantilla de descripci\u00f3n del puesto de ingeniero de seguridad de software est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet, y se podr\u00e1 personalizar f\u00e1cilmente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto\" \/>\n<meta property=\"og:site_name\" content=\"Recruiting Resources: How to Recruit and Hire Better\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/workable\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-08T11:04:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-06T13:23:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/software-security-engineer-640x230.jpg\" \/>\n<meta name=\"author\" content=\"Eleni Kourmentza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@workable\" \/>\n<meta name=\"twitter:site\" content=\"@workable\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eleni Kourmentza\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-seguridad-de-software-descripcion-del-puesto#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-seguridad-de-software-descripcion-del-puesto\"},\"author\":{\"name\":\"Eleni Kourmentza\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/person\\\/246aec99718ddcb172f71f699e088a88\"},\"headline\":\"Descripci\u00f3n del puesto: Ingeniero de seguridad de software&nbsp;(m\\\/h\\\/x)\",\"datePublished\":\"2020-01-08T11:04:52+00:00\",\"dateModified\":\"2020-02-06T13:23:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-seguridad-de-software-descripcion-del-puesto\"},\"wordCount\":110,\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-seguridad-de-software-descripcion-del-puesto#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/software-security-engineer-640x230.jpg\",\"keywords\":[\"inform\u00e1tica-muestra\"],\"articleSection\":[\"Descripciones de funciones\",\"Descripciones de funciones de puestos de TI y desarrollo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-seguridad-de-software-descripcion-del-puesto\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-seguridad-de-software-descripcion-del-puesto\",\"name\":\"Plantilla de descripci\u00f3n del puesto de ingeniero de seguridad de software | Workable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-seguridad-de-software-descripcion-del-puesto#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-seguridad-de-software-descripcion-del-puesto#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/software-security-engineer-640x230.jpg\",\"datePublished\":\"2020-01-08T11:04:52+00:00\",\"dateModified\":\"2020-02-06T13:23:00+00:00\",\"description\":\"Esta plantilla de descripci\u00f3n del puesto de ingeniero de seguridad de software est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet, y se podr\u00e1 personalizar f\u00e1cilmente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-seguridad-de-software-descripcion-del-puesto#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-seguridad-de-software-descripcion-del-puesto\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-seguridad-de-software-descripcion-del-puesto#primaryimage\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/software-security-engineer-640x230.jpg\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/software-security-engineer-640x230.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/ingeniero-de-seguridad-de-software-descripcion-del-puesto#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descripci\u00f3n del puesto: Ingeniero de seguridad de software&nbsp;(m\\\/h\\\/x)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/\",\"name\":\"Recruiting Resources: How to Recruit and Hire Better\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#organization\",\"name\":\"Workable\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"width\":150,\"height\":25,\"caption\":\"Workable\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/business.facebook.com\\\/workable\\\/\",\"https:\\\/\\\/x.com\\\/workable\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/workable-hr\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/#\\\/schema\\\/person\\\/246aec99718ddcb172f71f699e088a88\",\"name\":\"Eleni Kourmentza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg\",\"caption\":\"Eleni Kourmentza\"},\"description\":\"Eleni Kourmentza, ex-People Ops Manager at Workable, excelled in recruitment, lifecycle management, HR admin, culture nurturing, and employer branding.\",\"sameAs\":[\"http:\\\/\\\/workable.com\"],\"url\":\"https:\\\/\\\/resources.workable.com\\\/es\\\/author\\\/eleni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Plantilla de descripci\u00f3n del puesto de ingeniero de seguridad de software | Workable","description":"Esta plantilla de descripci\u00f3n del puesto de ingeniero de seguridad de software est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet, y se podr\u00e1 personalizar f\u00e1cilmente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto\/","og_locale":"es_ES","og_type":"article","og_title":"Descripci\u00f3n del puesto: Ingeniero de seguridad de software (m\/h\/x)","og_description":"Esta plantilla de descripci\u00f3n del puesto de ingeniero de seguridad de software est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet, y se podr\u00e1 personalizar f\u00e1cilmente.","og_url":"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto","og_site_name":"Recruiting Resources: How to Recruit and Hire Better","article_publisher":"https:\/\/business.facebook.com\/workable\/","article_published_time":"2020-01-08T11:04:52+00:00","article_modified_time":"2020-02-06T13:23:00+00:00","og_image":[{"url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/software-security-engineer-640x230.jpg","type":"","width":"","height":""}],"author":"Eleni Kourmentza","twitter_card":"summary_large_image","twitter_creator":"@workable","twitter_site":"@workable","twitter_misc":{"Escrito por":"Eleni Kourmentza"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto#article","isPartOf":{"@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto"},"author":{"name":"Eleni Kourmentza","@id":"https:\/\/resources.workable.com\/es\/#\/schema\/person\/246aec99718ddcb172f71f699e088a88"},"headline":"Descripci\u00f3n del puesto: Ingeniero de seguridad de software&nbsp;(m\/h\/x)","datePublished":"2020-01-08T11:04:52+00:00","dateModified":"2020-02-06T13:23:00+00:00","mainEntityOfPage":{"@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto"},"wordCount":110,"publisher":{"@id":"https:\/\/resources.workable.com\/es\/#organization"},"image":{"@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/software-security-engineer-640x230.jpg","keywords":["inform\u00e1tica-muestra"],"articleSection":["Descripciones de funciones","Descripciones de funciones de puestos de TI y desarrollo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto","url":"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto","name":"Plantilla de descripci\u00f3n del puesto de ingeniero de seguridad de software | Workable","isPartOf":{"@id":"https:\/\/resources.workable.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto#primaryimage"},"image":{"@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/software-security-engineer-640x230.jpg","datePublished":"2020-01-08T11:04:52+00:00","dateModified":"2020-02-06T13:23:00+00:00","description":"Esta plantilla de descripci\u00f3n del puesto de ingeniero de seguridad de software est\u00e1 optimizada para su publicaci\u00f3n en bolsas de trabajo y p\u00e1ginas de empleo en Internet, y se podr\u00e1 personalizar f\u00e1cilmente.","breadcrumb":{"@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto#primaryimage","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/software-security-engineer-640x230.jpg","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/07\/software-security-engineer-640x230.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/resources.workable.com\/es\/ingeniero-de-seguridad-de-software-descripcion-del-puesto#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/resources.workable.com\/es\/"},{"@type":"ListItem","position":2,"name":"Descripci\u00f3n del puesto: Ingeniero de seguridad de software&nbsp;(m\/h\/x)"}]},{"@type":"WebSite","@id":"https:\/\/resources.workable.com\/es\/#website","url":"https:\/\/resources.workable.com\/es\/","name":"Recruiting Resources: How to Recruit and Hire Better","description":"","publisher":{"@id":"https:\/\/resources.workable.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/resources.workable.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/resources.workable.com\/es\/#organization","name":"Workable","url":"https:\/\/resources.workable.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/resources.workable.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","width":150,"height":25,"caption":"Workable"},"image":{"@id":"https:\/\/resources.workable.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/workable\/","https:\/\/x.com\/workable","https:\/\/www.linkedin.com\/company\/workable-hr\/"]},{"@type":"Person","@id":"https:\/\/resources.workable.com\/es\/#\/schema\/person\/246aec99718ddcb172f71f699e088a88","name":"Eleni Kourmentza","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg","caption":"Eleni Kourmentza"},"description":"Eleni Kourmentza, ex-People Ops Manager at Workable, excelled in recruitment, lifecycle management, HR admin, culture nurturing, and employer branding.","sameAs":["http:\/\/workable.com"],"url":"https:\/\/resources.workable.com\/es\/author\/eleni\/"}]}},"modified_by":"Alexandra Marinaki","custom_fields":{"brief":"Buscamos un ingeniero de seguridad cualificado para analizar los dise\u00f1os e implementaciones de software desde el punto de vista de la seguridad, e identificar y solucionar problemas de seguridad. Incluir\u00e1s los an\u00e1lisis de seguridad, las defensas y las contramedidas apropiados en cada fase del ciclo de vida de desarrollo de software, para producir un software fiable y robusto.","requirements":"<ul>\r\n \t<li>Experiencia laboral demostrada como ingeniero de seguridad de software<\/li>\r\n \t<li>Gran conocimiento t\u00e9cnico de t\u00e9cnicas, est\u00e1ndares y vanguardistas capacidades de autenticaci\u00f3n y autorizaci\u00f3n, criptograf\u00eda aplicada, vulnerabilidades en la seguridad y soluciones<\/li>\r\n \t<li>Experiencia desarrollando software en uno de los siguientes lenguajes: Ruby on Rails, Java, Javascript y .NET<\/li>\r\n \t<li>Conocimientos adecuados de tecnolog\u00edas web (aplicaciones web, servicios web y arquitecturas orientadas a servicios) y de protocolos web y de redes<\/li>\r\n \t<li>Sentir inter\u00e9s por todos los aspectos de la investigaci\u00f3n y desarrollo en materia de seguridad<\/li>\r\n \t<li>Grado en ciencias inform\u00e1ticas o en un campo relacionado<\/li>\r\n<\/ul>","responsibilities":"<ul>\r\n \t<li>Implementar, probar y utilizar avanzadas t\u00e9cnicas de seguridad de software de acuerdo con la arquitectura de referencia t\u00e9cnica<\/li>\r\n \t<li>Realizar pruebas continuas de seguridad y revisar el c\u00f3digo para mejorar la seguridad del software<\/li>\r\n \t<li>Solucionar y depurar los problemas que surjan<\/li>\r\n \t<li>Elaborar dise\u00f1os de ingenier\u00eda para las nuevas soluciones de software que ayuden a mitigar las vulnerabilidades de seguridad<\/li>\r\n \t<li>Contribuir en todos los niveles de la arquitectura<\/li>\r\n \t<li>Mantener la documentaci\u00f3n t\u00e9cnica<\/li>\r\n \t<li>Consultar a los miembros del equipo sobre pr\u00e1cticas de codificaci\u00f3n seguras<\/li>\r\n \t<li>Familiarizarse con las nuevas herramientas y las buenas pr\u00e1cticas<\/li>\r\n<\/ul>","see_more":"<h2>M\u00e1s recursos:<\/h2>\r\n<ul>\r\n \t<li>Buscar y contratar a ingenieros de seguridad de software con las fichas de ayuda de <a href=\"https:\/\/resources.workable.com\/find-engineers-managers-boolean-search-strings\">b\u00fasqueda booleana<\/a> de Workable.<\/li>\r\n \t<li>Evaluar las habilidades y cualificaciones pertinentes con nuestras preguntas para la entrevista con el candidato a <a href=\"https:\/\/resources.workable.com\/system-engineer-interview-questions\">ingeniero de sistemas<\/a> o\u00a0<a href=\"https:\/\/resources.workable.com\/senior-software-engineer-interview-questions\">ingeniero de software<\/a>.<\/li>\r\n<\/ul>"},"_links":{"self":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/posts\/40873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/comments?post=40873"}],"version-history":[{"count":0,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/posts\/40873\/revisions"}],"wp:attachment":[{"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/media?parent=40873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/categories?post=40873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resources.workable.com\/es\/wp-json\/wp\/v2\/tags?post=40873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}