{"id":63942,"date":"2020-01-08T11:14:10","date_gmt":"2020-01-08T11:14:10","guid":{"rendered":"https:\/\/resources.workable.com\/?p=63942"},"modified":"2020-02-06T13:14:01","modified_gmt":"2020-02-06T13:14:01","slug":"stellenbeschreibung-manager-fuer-diversitaet-und-integration-m-w-d","status":"publish","type":"post","link":"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung","title":{"rendered":"Stellenbeschreibung: Manager f\u00fcr Diversit\u00e4t und Integration&nbsp;(m\/w\/d)"},"content":{"rendered":"<p>Verwenden Sie diese Vorlage f\u00fcr die Stellenbeschreibung Manager f\u00fcr Diversit\u00e4t und Integration, um qualifizierte Personalfachkr\u00e4fte zu gewinnen und einzustellen.<\/p>\n<h2>Zu den Aufgaben eines Managers f\u00fcr Diversit\u00e4t und Integration geh\u00f6ren:<\/h2>\n<ul>\n<li>Entwickeln von Unternehmensrichtlinien, die die Diversit\u00e4t am Arbeitsplatz verst\u00e4rken, alle Arten von Bel\u00e4stigung unterbinden sowie Minderheiten sch\u00fctzen<\/li>\n<li>Schulen rekrutierender F\u00fchrungskr\u00e4fte und Mitarbeiter der Personalabteilung, wie sie unterschiedliche Mitarbeiter ausw\u00e4hlen, f\u00fchren, beurteilen und binden<\/li>\n<li>Pr\u00fcfen und Aktualisieren unserer Stellenbeschreibungen, um sicherzustellen, dass wir eine diskriminierungsfreie Sprache verwenden<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30907 alignnone\" src=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2018\/03\/shutterstock_708284185.jpg\" alt=\"Stellenbeschreibung Manager f\u00fcr Diversit\u00e4t und Integration\" width=\"640\" height=\"230\" srcset=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2018\/03\/shutterstock_708284185.jpg 640w, https:\/\/resources.workable.com\/wp-content\/uploads\/2018\/03\/shutterstock_708284185-200x72.jpg 200w, https:\/\/resources.workable.com\/wp-content\/uploads\/2018\/03\/shutterstock_708284185-560x201.jpg 560w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Verwenden Sie diese Vorlage f\u00fcr die Stellenbeschreibung Manager f\u00fcr Diversit\u00e4t und Integration, um qualifizierte Personalfachkr\u00e4fte zu gewinnen und einzustellen. Zu den Aufgaben eines Managers f\u00fcr Diversit\u00e4t und Integration geh\u00f6ren: Entwickeln von Unternehmensrichtlinien, die die Diversit\u00e4t am Arbeitsplatz verst\u00e4rken, alle Arten von Bel\u00e4stigung unterbinden sowie Minderheiten sch\u00fctzen Schulen rekrutierender F\u00fchrungskr\u00e4fte und Mitarbeiter der Personalabteilung, wie sie [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"no","_lmt_disable":"","_has_post_settings":[],"footnotes":""},"categories":[1044,1339],"tags":[],"class_list":["post-63942","post","type-post","status-publish","format-standard","hentry","category-stellenbeschreibungen","category-stellenbeschreibungen-personalwesen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vorlage f\u00fcr die Stellenbeschreibung Manager f\u00fcr Diversit\u00e4t und Integration | Workable<\/title>\n<meta name=\"description\" content=\"Verwenden Sie diese Vorlage f\u00fcr die Stellenbeschreibung Manager f\u00fcr Diversit\u00e4t und Integration, um qualifizierte Personalfachkr\u00e4fte zu gewinnen und einzustellen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vorlage f\u00fcr die Stellenbeschreibung Manager f\u00fcr Diversit\u00e4t und Integration | Workable\" \/>\n<meta property=\"og:description\" content=\"Verwenden Sie diese Vorlage f\u00fcr die Stellenbeschreibung Manager f\u00fcr Diversit\u00e4t und Integration, um qualifizierte Personalfachkr\u00e4fte zu gewinnen und einzustellen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung\" \/>\n<meta property=\"og:site_name\" content=\"Recruiting Resources: How to Recruit and Hire Better\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/workable\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-08T11:14:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-06T13:14:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2018\/03\/shutterstock_708284185.jpg\" \/>\n<meta name=\"author\" content=\"Christina Pavlou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@workable\" \/>\n<meta name=\"twitter:site\" content=\"@workable\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina Pavlou\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/manager-fuer-diversitaet-und-integration-stellenbeschreibung#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/manager-fuer-diversitaet-und-integration-stellenbeschreibung\"},\"author\":{\"name\":\"Christina Pavlou\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#\\\/schema\\\/person\\\/b23289d8d63331621eee9e69103cd603\"},\"headline\":\"Stellenbeschreibung: Manager f\u00fcr Diversit\u00e4t und Integration&nbsp;(m\\\/w\\\/d)\",\"datePublished\":\"2020-01-08T11:14:10+00:00\",\"dateModified\":\"2020-02-06T13:14:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/manager-fuer-diversitaet-und-integration-stellenbeschreibung\"},\"wordCount\":102,\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/manager-fuer-diversitaet-und-integration-stellenbeschreibung#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/shutterstock_708284185.jpg\",\"articleSection\":[\"Stellenbeschreibungen\",\"Stellenbeschreibungen Personalwesen\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/manager-fuer-diversitaet-und-integration-stellenbeschreibung\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/manager-fuer-diversitaet-und-integration-stellenbeschreibung\",\"name\":\"Vorlage f\u00fcr die Stellenbeschreibung Manager f\u00fcr Diversit\u00e4t und Integration | Workable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/manager-fuer-diversitaet-und-integration-stellenbeschreibung#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/manager-fuer-diversitaet-und-integration-stellenbeschreibung#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/shutterstock_708284185.jpg\",\"datePublished\":\"2020-01-08T11:14:10+00:00\",\"dateModified\":\"2020-02-06T13:14:01+00:00\",\"description\":\"Verwenden Sie diese Vorlage f\u00fcr die Stellenbeschreibung Manager f\u00fcr Diversit\u00e4t und Integration, um qualifizierte Personalfachkr\u00e4fte zu gewinnen und einzustellen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/manager-fuer-diversitaet-und-integration-stellenbeschreibung#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/resources.workable.com\\\/de\\\/manager-fuer-diversitaet-und-integration-stellenbeschreibung\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/manager-fuer-diversitaet-und-integration-stellenbeschreibung#primaryimage\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/shutterstock_708284185.jpg\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/shutterstock_708284185.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/manager-fuer-diversitaet-und-integration-stellenbeschreibung#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stellenbeschreibung: Manager f\u00fcr Diversit\u00e4t und Integration&nbsp;(m\\\/w\\\/d)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/\",\"name\":\"Recruiting Resources: How to Recruit and Hire Better\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#organization\",\"name\":\"Workable\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"width\":150,\"height\":25,\"caption\":\"Workable\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/business.facebook.com\\\/workable\\\/\",\"https:\\\/\\\/x.com\\\/workable\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/workable-hr\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#\\\/schema\\\/person\\\/b23289d8d63331621eee9e69103cd603\",\"name\":\"Christina Pavlou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg\",\"caption\":\"Christina Pavlou\"},\"description\":\"Christina Pavlou was a writer at Workable for nearly four years, and previously a recruiter. She writes about diversity in the workplace and reports on the shape of things to come. You can find her on LinkedIn and Twitter.\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/author\\\/christina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vorlage f\u00fcr die Stellenbeschreibung Manager f\u00fcr Diversit\u00e4t und Integration | Workable","description":"Verwenden Sie diese Vorlage f\u00fcr die Stellenbeschreibung Manager f\u00fcr Diversit\u00e4t und Integration, um qualifizierte Personalfachkr\u00e4fte zu gewinnen und einzustellen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung\/","og_locale":"de_DE","og_type":"article","og_title":"Vorlage f\u00fcr die Stellenbeschreibung Manager f\u00fcr Diversit\u00e4t und Integration | Workable","og_description":"Verwenden Sie diese Vorlage f\u00fcr die Stellenbeschreibung Manager f\u00fcr Diversit\u00e4t und Integration, um qualifizierte Personalfachkr\u00e4fte zu gewinnen und einzustellen.","og_url":"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung","og_site_name":"Recruiting Resources: How to Recruit and Hire Better","article_publisher":"https:\/\/business.facebook.com\/workable\/","article_published_time":"2020-01-08T11:14:10+00:00","article_modified_time":"2020-02-06T13:14:01+00:00","og_image":[{"url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2018\/03\/shutterstock_708284185.jpg","type":"","width":"","height":""}],"author":"Christina Pavlou","twitter_card":"summary_large_image","twitter_creator":"@workable","twitter_site":"@workable","twitter_misc":{"Verfasst von":"Christina Pavlou"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung#article","isPartOf":{"@id":"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung"},"author":{"name":"Christina Pavlou","@id":"https:\/\/resources.workable.com\/de\/#\/schema\/person\/b23289d8d63331621eee9e69103cd603"},"headline":"Stellenbeschreibung: Manager f\u00fcr Diversit\u00e4t und Integration&nbsp;(m\/w\/d)","datePublished":"2020-01-08T11:14:10+00:00","dateModified":"2020-02-06T13:14:01+00:00","mainEntityOfPage":{"@id":"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung"},"wordCount":102,"publisher":{"@id":"https:\/\/resources.workable.com\/de\/#organization"},"image":{"@id":"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2018\/03\/shutterstock_708284185.jpg","articleSection":["Stellenbeschreibungen","Stellenbeschreibungen Personalwesen"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung","url":"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung","name":"Vorlage f\u00fcr die Stellenbeschreibung Manager f\u00fcr Diversit\u00e4t und Integration | Workable","isPartOf":{"@id":"https:\/\/resources.workable.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung#primaryimage"},"image":{"@id":"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2018\/03\/shutterstock_708284185.jpg","datePublished":"2020-01-08T11:14:10+00:00","dateModified":"2020-02-06T13:14:01+00:00","description":"Verwenden Sie diese Vorlage f\u00fcr die Stellenbeschreibung Manager f\u00fcr Diversit\u00e4t und Integration, um qualifizierte Personalfachkr\u00e4fte zu gewinnen und einzustellen.","breadcrumb":{"@id":"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung#primaryimage","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2018\/03\/shutterstock_708284185.jpg","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2018\/03\/shutterstock_708284185.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/resources.workable.com\/de\/manager-fuer-diversitaet-und-integration-stellenbeschreibung#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/resources.workable.com\/de\/"},{"@type":"ListItem","position":2,"name":"Stellenbeschreibung: Manager f\u00fcr Diversit\u00e4t und Integration&nbsp;(m\/w\/d)"}]},{"@type":"WebSite","@id":"https:\/\/resources.workable.com\/de\/#website","url":"https:\/\/resources.workable.com\/de\/","name":"Recruiting Resources: How to Recruit and Hire Better","description":"","publisher":{"@id":"https:\/\/resources.workable.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/resources.workable.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/resources.workable.com\/de\/#organization","name":"Workable","url":"https:\/\/resources.workable.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/resources.workable.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","width":150,"height":25,"caption":"Workable"},"image":{"@id":"https:\/\/resources.workable.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/workable\/","https:\/\/x.com\/workable","https:\/\/www.linkedin.com\/company\/workable-hr\/"]},{"@type":"Person","@id":"https:\/\/resources.workable.com\/de\/#\/schema\/person\/b23289d8d63331621eee9e69103cd603","name":"Christina Pavlou","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ed48272d268bb7071cf243f8d2dcaeaa1f26feca5ecd3fbed59e0378447bc49?s=96&d=mm&r=pg","caption":"Christina Pavlou"},"description":"Christina Pavlou was a writer at Workable for nearly four years, and previously a recruiter. She writes about diversity in the workplace and reports on the shape of things to come. You can find her on LinkedIn and Twitter.","url":"https:\/\/resources.workable.com\/de\/author\/christina\/"}]}},"modified_by":"Christina Pavlou","custom_fields":{"brief":"Wir suchen einen Manager f\u00fcr Diversit\u00e4t und Integration zum F\u00f6rdern eines unterst\u00fctzenden und integrativen Arbeitsumfelds f\u00fcr alle Mitarbeiter.\r\n\r\nZu den Aufgaben eines Managers f\u00fcr Diversit\u00e4t und Integration geh\u00f6ren das Erstellen fairer Unternehmensrichtlinien, das Implementieren von Integrationsprogrammen und das Anwenden objektiver Einstellungskriterien. Um in dieser Position erfolgreich zu sein, sollten Sie \u00fcber Erfahrung im Personalwesen sowie \u00fcber Kenntnisse im Bereich Menschenrechte verf\u00fcgen.\r\n\r\nSchlie\u00dflich werden Sie in dieser Funktion sicherstellen, dass wir gleiche Besch\u00e4ftigungschancen f\u00fcr alle Kandidaten und Mitarbeiter ungeachtet ihrer gesch\u00fctzten Merkmale bieten.","requirements":"<ul>\r\n \t<li>Berufserfahrung als <a href=\"https:\/\/resources.workable.com\/hr-manager-job-description\" target=\"_blank\" rel=\"noopener\">Leiter Personalwesen<\/a>, <a href=\"https:\/\/resources.workable.com\/hr-consultant-job-description\" target=\"_blank\" rel=\"noopener\">Personalberater<\/a> oder in einer \u00e4hnlichen Funktion<\/li>\r\n \t<li>Praktische Erfahrung im Erarbeiten von Unternehmensrichtlinien zu <a href=\"https:\/\/resources.workable.com\/hr-manager-job-description\" target=\"_blank\" rel=\"noopener\">Antidiskriminierung<\/a> und <a href=\"https:\/\/resources.workable.com\/equal-opportunity-company-policy\" target=\"_blank\" rel=\"noopener\">beruflicher Chancengleichheit<\/a><\/li>\r\n \t<li>Gute Kenntnisse des Arbeitsrechts und der Menschenrechtsgesetze<\/li>\r\n \t<li>Teilnahme an Seminaren \u00fcber Diversit\u00e4t am Arbeitsplatz ist von Vorteil<\/li>\r\n \t<li>Ausgezeichnete Kommunikationsf\u00e4higkeiten<\/li>\r\n \t<li>F\u00fchrungsqualit\u00e4ten<\/li>\r\n \t<li>Bachelor-Abschluss in Personalwirtschaft, Unternehmenspsychologie oder in einem relevanten Bereich<\/li>\r\n<\/ul>","responsibilities":"<ul>\r\n \t<li>Entwickeln von Unternehmensrichtlinien, die die Diversit\u00e4t am Arbeitsplatz verst\u00e4rken, alle Arten von Bel\u00e4stigungen unterbinden sowie Frauen und Minderheiten sch\u00fctzen<\/li>\r\n \t<li>Schulen rekrutierender F\u00fchrungskr\u00e4fte und Mitarbeiter der Personalabteilung, wie sie unterschiedliche Mitarbeiter ausw\u00e4hlen, f\u00fchren, beurteilen und binden<\/li>\r\n \t<li>\u00dcberarbeiten und Aktualisieren jeglicher Kommunikation auf unserer Website, auf Social-Media-Seiten, in Stellenbeschreibungen und in internen Unterlagen, um sicherzustellen, dass wir eine diskriminierungsfreie Sprache verwenden<\/li>\r\n \t<li>Pr\u00fcfen, dass unsere Auswahlkriterien objektiv und strikt aufgabengebunden sind<\/li>\r\n \t<li>Empfehlen von Sozialleistungspaketen, die alle Mitarbeiter ansprechen<\/li>\r\n \t<li>Messen und Prognostizieren von Diversit\u00e4ts-Kennzahlen<\/li>\r\n \t<li>Agieren als Berater f\u00fcr unterrepr\u00e4sentierte Gruppen und Sicherstellen, dass alle Stimmen geh\u00f6rt werden<\/li>\r\n \t<li>Organisieren von Schulungen zur Verbesserung der Kommunikationsf\u00e4higkeiten der Mitarbeiter und zur F\u00f6rderung des Teamgeists<\/li>\r\n \t<li>Repr\u00e4sentieren unseres Unternehmens bei verschiedenen Karriereveranstaltungen (wie Jobmessen)<\/li>\r\n \t<li>Sicherstellen der Einhaltung nationaler Vorschriften zu Diversit\u00e4t und Chancengleichheit<\/li>\r\n<\/ul>","see_more":""},"_links":{"self":[{"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/posts\/63942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/comments?post=63942"}],"version-history":[{"count":0,"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/posts\/63942\/revisions"}],"wp:attachment":[{"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/media?parent=63942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/categories?post=63942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/tags?post=63942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}