{"id":61148,"date":"2020-01-08T11:13:06","date_gmt":"2020-01-08T11:13:06","guid":{"rendered":"https:\/\/resources.workable.com\/?p=61148"},"modified":"2020-02-06T13:17:25","modified_gmt":"2020-02-06T13:17:25","slug":"stellenbeschreibung-maschinenbauingenieur-m-w-d","status":"publish","type":"post","link":"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung","title":{"rendered":"Stellenbeschreibung: Maschinenbauingenieur&nbsp;(m\/w\/d)"},"content":{"rendered":"<p>Diese Vorlage f\u00fcr die Stellenbeschreibung Maschinenbauingenieur ist f\u00fcr die Ver\u00f6ffentlichung in Online-Stellenb\u00f6rsen oder auf Karriereseiten optimiert und kann leicht durch das Hinzuf\u00fcgen von wichtigen Aufgaben und Pflichten an die Bed\u00fcrfnisse Ihres Unternehmens angepasst werden. Sie kann ge\u00e4ndert werden, um eine andere Ingenieurrolle einzustellen.<\/p>\n<h2>Die Aufgaben eines Maschinenbauingenieurs umfassen:<\/h2>\n<ul>\n<li>Durchf\u00fchrung eines vollst\u00e4ndigen Lebenszyklus einer Produktentwicklung<\/li>\n<li>Konstruktion von Systemen und Komponenten, die Bed\u00fcrfnissen und Anforderungen gerecht werden<\/li>\n<li>Methodische Durchf\u00fchrung von Experimenten, Analyse von Daten und Auswertung von Ergebnissen<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-61162 aligncenter\" src=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/mechanical-engineer-640x230.jpg\" alt=\"Stellenbeschreibung Maschinenbauingenieur\" width=\"640\" height=\"230\" srcset=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/mechanical-engineer.jpg 640w, https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/mechanical-engineer-200x72.jpg 200w, https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/mechanical-engineer-560x201.jpg 560w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diese Vorlage f\u00fcr die Stellenbeschreibung Maschinenbauingenieur ist f\u00fcr die Ver\u00f6ffentlichung in Online-Stellenb\u00f6rsen oder auf Karriereseiten optimiert und kann leicht durch das Hinzuf\u00fcgen von wichtigen Aufgaben und Pflichten an die Bed\u00fcrfnisse Ihres Unternehmens angepasst werden. Sie kann ge\u00e4ndert werden, um eine andere Ingenieurrolle einzustellen. Die Aufgaben eines Maschinenbauingenieurs umfassen: Durchf\u00fchrung eines vollst\u00e4ndigen Lebenszyklus einer Produktentwicklung Konstruktion [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"no","_lmt_disable":"","_has_post_settings":[],"footnotes":""},"categories":[1044,1226],"tags":[1350],"class_list":["post-61148","post","type-post","status-publish","format-standard","hentry","category-stellenbeschreibungen","category-stellenbeschreibungen-maschinenbau","tag-sample-engineering-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vorlage Stellenbeschreibung Maschinenbauingenieur | Workable<\/title>\n<meta name=\"description\" content=\"Diese Vorlage f\u00fcr die Stellenbeschreibung Maschinenbauingenieur ist f\u00fcr die Ver\u00f6ffentlichung in Online-Stellenb\u00f6rsen oder auf Karriereseiten optimiert und kann leicht an die Bed\u00fcrfnisse Ihres Unternehmens angepasst werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stellenbeschreibung: Maschinenbauingenieur (m\/w\/d)\" \/>\n<meta property=\"og:description\" content=\"Diese Vorlage f\u00fcr die Stellenbeschreibung Maschinenbauingenieur ist f\u00fcr die Ver\u00f6ffentlichung in Online-Stellenb\u00f6rsen oder auf Karriereseiten optimiert und kann leicht an die Bed\u00fcrfnisse Ihres Unternehmens angepasst werden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung\" \/>\n<meta property=\"og:site_name\" content=\"Recruiting Resources: How to Recruit and Hire Better\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/workable\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-08T11:13:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-06T13:17:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/mechanical-engineer-640x230.jpg\" \/>\n<meta name=\"author\" content=\"Eleni Kourmentza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@workable\" \/>\n<meta name=\"twitter:site\" content=\"@workable\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eleni Kourmentza\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/maschinenbauingenieur-stellenbeschreibung#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/maschinenbauingenieur-stellenbeschreibung\"},\"author\":{\"name\":\"Eleni Kourmentza\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#\\\/schema\\\/person\\\/246aec99718ddcb172f71f699e088a88\"},\"headline\":\"Stellenbeschreibung: Maschinenbauingenieur&nbsp;(m\\\/w\\\/d)\",\"datePublished\":\"2020-01-08T11:13:06+00:00\",\"dateModified\":\"2020-02-06T13:17:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/maschinenbauingenieur-stellenbeschreibung\"},\"wordCount\":92,\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/maschinenbauingenieur-stellenbeschreibung#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/mechanical-engineer-640x230.jpg\",\"keywords\":[\"sample-engineering\"],\"articleSection\":[\"Stellenbeschreibungen\",\"Stellenbeschreibungen Maschinenbau\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/maschinenbauingenieur-stellenbeschreibung\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/maschinenbauingenieur-stellenbeschreibung\",\"name\":\"Vorlage Stellenbeschreibung Maschinenbauingenieur | Workable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/maschinenbauingenieur-stellenbeschreibung#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/maschinenbauingenieur-stellenbeschreibung#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/mechanical-engineer-640x230.jpg\",\"datePublished\":\"2020-01-08T11:13:06+00:00\",\"dateModified\":\"2020-02-06T13:17:25+00:00\",\"description\":\"Diese Vorlage f\u00fcr die Stellenbeschreibung Maschinenbauingenieur ist f\u00fcr die Ver\u00f6ffentlichung in Online-Stellenb\u00f6rsen oder auf Karriereseiten optimiert und kann leicht an die Bed\u00fcrfnisse Ihres Unternehmens angepasst werden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/maschinenbauingenieur-stellenbeschreibung#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/resources.workable.com\\\/de\\\/maschinenbauingenieur-stellenbeschreibung\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/maschinenbauingenieur-stellenbeschreibung#primaryimage\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/mechanical-engineer-640x230.jpg\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2013\\\/08\\\/mechanical-engineer-640x230.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/maschinenbauingenieur-stellenbeschreibung#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stellenbeschreibung: Maschinenbauingenieur&nbsp;(m\\\/w\\\/d)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/\",\"name\":\"Recruiting Resources: How to Recruit and Hire Better\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#organization\",\"name\":\"Workable\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"contentUrl\":\"https:\\\/\\\/resources.workable.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo-green.png\",\"width\":150,\"height\":25,\"caption\":\"Workable\"},\"image\":{\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/business.facebook.com\\\/workable\\\/\",\"https:\\\/\\\/x.com\\\/workable\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/workable-hr\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/#\\\/schema\\\/person\\\/246aec99718ddcb172f71f699e088a88\",\"name\":\"Eleni Kourmentza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg\",\"caption\":\"Eleni Kourmentza\"},\"description\":\"Eleni Kourmentza, ex-People Ops Manager at Workable, excelled in recruitment, lifecycle management, HR admin, culture nurturing, and employer branding.\",\"sameAs\":[\"http:\\\/\\\/workable.com\"],\"url\":\"https:\\\/\\\/resources.workable.com\\\/de\\\/author\\\/eleni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vorlage Stellenbeschreibung Maschinenbauingenieur | Workable","description":"Diese Vorlage f\u00fcr die Stellenbeschreibung Maschinenbauingenieur ist f\u00fcr die Ver\u00f6ffentlichung in Online-Stellenb\u00f6rsen oder auf Karriereseiten optimiert und kann leicht an die Bed\u00fcrfnisse Ihres Unternehmens angepasst werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung\/","og_locale":"de_DE","og_type":"article","og_title":"Stellenbeschreibung: Maschinenbauingenieur (m\/w\/d)","og_description":"Diese Vorlage f\u00fcr die Stellenbeschreibung Maschinenbauingenieur ist f\u00fcr die Ver\u00f6ffentlichung in Online-Stellenb\u00f6rsen oder auf Karriereseiten optimiert und kann leicht an die Bed\u00fcrfnisse Ihres Unternehmens angepasst werden.","og_url":"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung","og_site_name":"Recruiting Resources: How to Recruit and Hire Better","article_publisher":"https:\/\/business.facebook.com\/workable\/","article_published_time":"2020-01-08T11:13:06+00:00","article_modified_time":"2020-02-06T13:17:25+00:00","og_image":[{"url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/mechanical-engineer-640x230.jpg","type":"","width":"","height":""}],"author":"Eleni Kourmentza","twitter_card":"summary_large_image","twitter_creator":"@workable","twitter_site":"@workable","twitter_misc":{"Verfasst von":"Eleni Kourmentza"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung#article","isPartOf":{"@id":"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung"},"author":{"name":"Eleni Kourmentza","@id":"https:\/\/resources.workable.com\/de\/#\/schema\/person\/246aec99718ddcb172f71f699e088a88"},"headline":"Stellenbeschreibung: Maschinenbauingenieur&nbsp;(m\/w\/d)","datePublished":"2020-01-08T11:13:06+00:00","dateModified":"2020-02-06T13:17:25+00:00","mainEntityOfPage":{"@id":"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung"},"wordCount":92,"publisher":{"@id":"https:\/\/resources.workable.com\/de\/#organization"},"image":{"@id":"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/mechanical-engineer-640x230.jpg","keywords":["sample-engineering"],"articleSection":["Stellenbeschreibungen","Stellenbeschreibungen Maschinenbau"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung","url":"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung","name":"Vorlage Stellenbeschreibung Maschinenbauingenieur | Workable","isPartOf":{"@id":"https:\/\/resources.workable.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung#primaryimage"},"image":{"@id":"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung#primaryimage"},"thumbnailUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/mechanical-engineer-640x230.jpg","datePublished":"2020-01-08T11:13:06+00:00","dateModified":"2020-02-06T13:17:25+00:00","description":"Diese Vorlage f\u00fcr die Stellenbeschreibung Maschinenbauingenieur ist f\u00fcr die Ver\u00f6ffentlichung in Online-Stellenb\u00f6rsen oder auf Karriereseiten optimiert und kann leicht an die Bed\u00fcrfnisse Ihres Unternehmens angepasst werden.","breadcrumb":{"@id":"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung#primaryimage","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/mechanical-engineer-640x230.jpg","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2013\/08\/mechanical-engineer-640x230.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/resources.workable.com\/de\/maschinenbauingenieur-stellenbeschreibung#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/resources.workable.com\/de\/"},{"@type":"ListItem","position":2,"name":"Stellenbeschreibung: Maschinenbauingenieur&nbsp;(m\/w\/d)"}]},{"@type":"WebSite","@id":"https:\/\/resources.workable.com\/de\/#website","url":"https:\/\/resources.workable.com\/de\/","name":"Recruiting Resources: How to Recruit and Hire Better","description":"","publisher":{"@id":"https:\/\/resources.workable.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/resources.workable.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/resources.workable.com\/de\/#organization","name":"Workable","url":"https:\/\/resources.workable.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/resources.workable.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","contentUrl":"https:\/\/resources.workable.com\/wp-content\/uploads\/2017\/12\/logo-green.png","width":150,"height":25,"caption":"Workable"},"image":{"@id":"https:\/\/resources.workable.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/workable\/","https:\/\/x.com\/workable","https:\/\/www.linkedin.com\/company\/workable-hr\/"]},{"@type":"Person","@id":"https:\/\/resources.workable.com\/de\/#\/schema\/person\/246aec99718ddcb172f71f699e088a88","name":"Eleni Kourmentza","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9941ca019d8b6c20633797a6b788bfc4b438c79e45a22797c9abfc4bfd997e7d?s=96&d=mm&r=pg","caption":"Eleni Kourmentza"},"description":"Eleni Kourmentza, ex-People Ops Manager at Workable, excelled in recruitment, lifecycle management, HR admin, culture nurturing, and employer branding.","sameAs":["http:\/\/workable.com"],"url":"https:\/\/resources.workable.com\/de\/author\/eleni\/"}]}},"modified_by":"Zina Panagopoulou","custom_fields":{"brief":"<p dir=\"ltr\">Wir suchen nach einem kreativen Maschinenbauingenieur, um in allen Produktphasen von der Forschung und Entwicklung \u00fcber die Konstruktion und Herstellung bis hin zur Installation und endg\u00fcltigen Inbetriebnahme zu arbeiten.\u00a0Das Ziel ist es, innovative und ausgezeichnete mechanische Komponenten zu entwerfen und zu fertigen.<\/p>","requirements":"<ul>\r\n \t<li>Nachgewiesene Arbeitserfahrung im Maschinenbau<\/li>\r\n \t<li>Arbeitserfahrung mit dem Produktlebenszyklus-Management (PLM), der Finite-Elemente-Analyse (FEA) und der numerischen Str\u00f6mungsmechanik (CFD)<\/li>\r\n \t<li>Praktische Erfahrung mit der computergest\u00fctzten Entwicklung (CAE) und der computergest\u00fctzten Fertigung (CAM)<\/li>\r\n \t<li>Vertrautheit mit 2D- oder 3D-Ingenieurdesign- und -fertigungstools (z. B., AutoCAD, ProE oder andere)<\/li>\r\n \t<li>Ausreichende Kenntnisse von Ingenieuranalysetools (ANSYS, ProMechanica, o.\u00e4.)<\/li>\r\n \t<li>Kenntnisse von mathematischen Berechnungs- und Analysetools (Matlab, Excel, LabView, usw.)<\/li>\r\n \t<li>Gutes Verst\u00e4ndnis der Kernkonzepte, einschlie\u00dflich Mechanik, Kinematik, Thermodynamik, Materialwissenschaften, usw.<\/li>\r\n \t<li>Kreativit\u00e4t und Analysef\u00e4higkeiten<\/li>\r\n \t<li>F\u00e4higkeit, technisches Wissen auf klare und verst\u00e4ndliche Weise zu vermitteln<\/li>\r\n \t<li>Technische Schreibf\u00e4higkeiten<\/li>\r\n \t<li>Bachelor-Abschluss in Ingenieurwissenschaften<\/li>\r\n<\/ul>","responsibilities":"<ul>\r\n \t<li>Durchf\u00fchrung eines vollst\u00e4ndigen Lebenszyklus einer Produktentwicklung (gestalten, entwickeln, Prototypen testen, herstellen und einf\u00fchren)<\/li>\r\n \t<li>Konstruktion von Systemen und Komponenten, die Bed\u00fcrfnissen und Anforderungen gerecht werden<\/li>\r\n \t<li>Produktion von Entwurfsdesigns<\/li>\r\n \t<li>Methodische Durchf\u00fchrung von Experimenten, Analyse von Daten und Auswertung von Ergebnissen<\/li>\r\n \t<li>Pr\u00fcfung und Auswertung theoretischer Entw\u00fcrfe<\/li>\r\n \t<li>Identifikation, Formulierung und Produktion effektiver L\u00f6sungen f\u00fcr auftretende Probleme<\/li>\r\n \t<li>Beurteilung der Gesamtleistung, Zuverl\u00e4ssigkeit und Sicherheit von Endprodukten<\/li>\r\n \t<li>\u00c4nderung und Modifikation von Entw\u00fcrfen, um Anforderungen zu erf\u00fcllen und Fehlfunktionen zu beseitigen<\/li>\r\n \t<li>Sch\u00e4tzung des Budgets und des Projektumfangs<\/li>\r\n \t<li>Erbitten von Beobachtungen der Bediener<\/li>\r\n \t<li>Vorbereitung von Produktberichten und Dokumentationen<\/li>\r\n \t<li>Teilnahme an Ma\u00dfnahmen zum lebenslangen Lernen und Entwicklung von neuen Theorien oder Methoden<\/li>\r\n<\/ul>","see_more":"<h2>Weitere Ressourcen:<\/h2>\r\n<ul>\r\n \t<li><a href=\"https:\/\/resources.workable.com\/find-engineers-managers-boolean-search-strings\">Beschaffen und Rekrutieren<\/a> von Maschinenbauingenieuren\u00a0mit den Spickzetteln der Booleschen Suche von Workable.<\/li>\r\n<\/ul>"},"_links":{"self":[{"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/posts\/61148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/comments?post=61148"}],"version-history":[{"count":0,"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/posts\/61148\/revisions"}],"wp:attachment":[{"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/media?parent=61148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/categories?post=61148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/resources.workable.com\/de\/wp-json\/wp\/v2\/tags?post=61148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}